{"id":9979,"date":"2019-05-20T09:27:56","date_gmt":"2019-05-20T08:27:56","guid":{"rendered":"http:\/\/www.masharif.com\/fr\/?p=9979"},"modified":"2019-05-20T09:27:56","modified_gmt":"2019-05-20T08:27:56","slug":"archives-commentaires-poetiques-de-mohamed-salah-ben-amor-36-poemes-de-france-bernard36-2-faire","status":"publish","type":"post","link":"https:\/\/www.masharif.com\/fr\/2019\/05\/20\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-36-poemes-de-france-bernard36-2-faire\/","title":{"rendered":"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor :36\u2013Les po\u00e8mes de France Bernard:36-2: Que faire\u2026"},"content":{"rendered":"<div id=\"attachment_9969\" style=\"width: 310px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/05\/10405558_10202081649145177_2788907240823377239_n.jpg\"><img aria-describedby=\"caption-attachment-9969\" loading=\"lazy\" class=\"wp-image-9969 size-medium\" src=\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/05\/10405558_10202081649145177_2788907240823377239_n-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/05\/10405558_10202081649145177_2788907240823377239_n-300x300.jpg 300w, https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/05\/10405558_10202081649145177_2788907240823377239_n-150x150.jpg 150w, https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/05\/10405558_10202081649145177_2788907240823377239_n-55x55.jpg 55w, https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/05\/10405558_10202081649145177_2788907240823377239_n.jpg 396w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-9969\" class=\"wp-caption-text\">France Bernard<\/p><\/div>\n<p>&nbsp;<\/p>\n<p><strong>Quand je\u00a0me mure dans l\u2019inaction<\/strong><\/p>\n<p><strong>Quand\u00a0la vie du dehors\u00a0m\u2019inonde<\/strong><\/p>\n<p><strong>Quand\u00a0je ne peux plus respirer le monde<\/strong><\/p>\n<p><strong>Quand mon\u00a0c\u0153ur bat dans la pulpe de mes mains<\/strong><\/p>\n<p><strong>Quand ma\u00a0musique perd ses partitions<\/strong><\/p>\n<p><strong>Je passe des heures au piano<\/strong><\/p>\n<p><strong>Tapotant sur\u00a0le d\u00e9saccord des touches<\/strong><\/p>\n<p><strong>J\u2019\u00e9tudie les sonates de l\u2019amour<\/strong><\/p>\n<p><strong>La musique classique s\u2019est \u00e9teinte<\/strong><\/p>\n<p><strong>Le clavier d\u2019ivoire s\u2019est referm\u00e9<\/strong><\/p>\n<p><strong>Dans la course des pleurs<\/strong><\/p>\n<p><strong>Le flux\u00a0s\u2019\u00e9coule en symphonie<br \/>\n<\/strong><\/p>\n<p><strong>Sur mes jours et dans mes nuits \u2026<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Ce titre me rappelle celui du fameux livre de L\u00e9nine, \u00e0 la diff\u00e9rence que l\u2019objet d\u2019incertitude chez ce leader politique russe, \u00e0 savoir le plan qu\u2019il devait mettre au point pour faire chuter le r\u00e9gime des Tsars \u00a0\u00e9tait \u00a0totalement oppos\u00e9 aux pr\u00e9occupations subjectives et personnelles de notre po\u00e9tesse qui se r\u00e9sument en un sentiment d\u2019incapacit\u00e9 de contrer l\u2019ennui et la monotonie, lesquels semblent \u00a0de plus en plus s\u2019\u00e9riger comme un v\u00e9ritable \u00a0mal de si\u00e8cle, cr\u00e9ant chez l\u2019individu une crise aigu\u00eb d\u2019adaptation et d\u2019accommodation avec le train-train quotidien. Cet \u00e9tat de g\u00e8ne qui semble, selon les propos de la locutrice, \u00eatre n\u00e9 d\u2019un fort attachement au go\u00fbt et au genre de vie classiques qui se trouvent aujourd\u2019hui malmen\u00e9s et presque supplant\u00e9s par de nouveaux styles et de nouvelles vocations sans qu&#8217;ils r\u00e9ussissent toutefois \u00a0\u00e0 s\u2019affirmer comme de solides alternatives \u00a0(<strong>je passe des heures au piano tapotant sur\u00a0le d\u00e9saccord des touches\u00a0j\u2019\u00e9tudie les sonates de l\u2019amour\u00a0la musique classique s\u2019est \u00e9teinte\u00a0le clavier d\u2019ivoire s\u2019est referm\u00e9<\/strong>). Sommes-nous ainsi en pr\u00e9sence d\u2019une \u00e2me ayant un go\u00fbt excessif pour le pass\u00e9 et qui \u00a0est \u00a0 fortement d\u00e9pays\u00e9e devant une nouvelle r\u00e9alit\u00e9 qu\u2019elle trouve d\u00e9form\u00e9e et d\u00e9figur\u00e9e\u00a0?<\/p>\n<p>Sur le plan stylistique, la po\u00e9tesse , pour rendre le caract\u00e8re pesant et stressant de l\u2019ennui , a , d\u2019un c\u00f4t\u00e9, us\u00e9 massivement de l\u2019hyperbole (<strong>je\u00a0me mure dans l\u2019inaction &#8211; la<\/strong> <strong>vie du dehors\u00a0m\u2019inonde -je ne peux plus respirer le monde &#8211;\u00a0mon\u00a0c\u0153ur bat dans la pulpe de mes mains\u2026etc.<\/strong> ) et de l\u2019autre, a mis\u00e9, d\u00e8s le d\u00e9but, sur les sonorit\u00e9s r\u00e9p\u00e9titives surtout l\u2019anaphore dans les cinq premiers vers( Quand\u00a0:5 fois) et le rythme interne\u00a0 par le recours \u00e0 l\u2019asynd\u00e8te c&#8217;est-\u00e0-dire\u00a0 l\u2019absence de conjonctions de coordination entre les phrases .<\/p>\n<p>Un po\u00e8me l\u00e9ger , \u00e0 haute charge \u00e9motionnelle, peignant un tableau m\u00e9lancolique , celui de l\u2019\u00e2me humaine \u00a0au d\u00e9but de \u00a0ce vingt-et-uni\u00e8me si\u00e8cle .<a href=\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/05\/10171777_10201942756753773_2097147600073051583_n.jpg\"><img loading=\"lazy\" class=\"alignnone size-medium wp-image-9980\" src=\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/05\/10171777_10201942756753773_2097147600073051583_n-300x240.jpg\" alt=\"\" width=\"300\" height=\"240\" srcset=\"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/05\/10171777_10201942756753773_2097147600073051583_n-300x240.jpg 300w, https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/05\/10171777_10201942756753773_2097147600073051583_n-768x614.jpg 768w, https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/05\/10171777_10201942756753773_2097147600073051583_n-1024x819.jpg 1024w, https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/05\/10171777_10201942756753773_2097147600073051583_n.jpg 1750w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Quand je\u00a0me mure dans l\u2019inaction Quand\u00a0la vie du dehors\u00a0m\u2019inonde Quand\u00a0je ne peux plus respirer le monde Quand mon\u00a0c\u0153ur bat dans la pulpe de mes mains Quand ma\u00a0musique perd ses partitions Je passe des heures au piano Tapotant sur\u00a0le d\u00e9saccord des touches J\u2019\u00e9tudie les sonates de l\u2019amour La musique classique s\u2019est \u00e9teinte Le clavier d\u2019ivoire &#8230;<\/p>\n","protected":false},"author":2,"featured_media":9969,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor :36\u2013Les po\u00e8mes de France Bernard:36-2: Que faire\u2026 - Culminances<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.masharif.com\/fr\/2019\/05\/20\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-36-poemes-de-france-bernard36-2-faire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor :36\u2013Les po\u00e8mes de France Bernard:36-2: Que faire\u2026 - Culminances\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Quand je\u00a0me mure dans l\u2019inaction Quand\u00a0la vie du dehors\u00a0m\u2019inonde Quand\u00a0je ne peux plus respirer le monde Quand mon\u00a0c\u0153ur bat dans la pulpe de mes mains Quand ma\u00a0musique perd ses partitions Je passe des heures au piano Tapotant sur\u00a0le d\u00e9saccord des touches J\u2019\u00e9tudie les sonates de l\u2019amour La musique classique s\u2019est \u00e9teinte Le clavier d\u2019ivoire ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.masharif.com\/fr\/2019\/05\/20\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-36-poemes-de-france-bernard36-2-faire\/\" \/>\n<meta property=\"og:site_name\" content=\"Culminances\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-20T08:27:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/05\/10405558_10202081649145177_2788907240823377239_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"396\" \/>\n\t<meta property=\"og:image:height\" content=\"396\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mohamed Salah Ben Amor\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mohamed Salah Ben Amor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.masharif.com\/fr\/#website\",\"url\":\"https:\/\/www.masharif.com\/fr\/\",\"name\":\"Culminances\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.masharif.com\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.masharif.com\/fr\/2019\/05\/20\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-36-poemes-de-france-bernard36-2-faire\/#primaryimage\",\"url\":\"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/05\/10405558_10202081649145177_2788907240823377239_n.jpg\",\"contentUrl\":\"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/05\/10405558_10202081649145177_2788907240823377239_n.jpg\",\"width\":396,\"height\":396},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.masharif.com\/fr\/2019\/05\/20\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-36-poemes-de-france-bernard36-2-faire\/\",\"url\":\"https:\/\/www.masharif.com\/fr\/2019\/05\/20\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-36-poemes-de-france-bernard36-2-faire\/\",\"name\":\"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor :36\u2013Les po\u00e8mes de France Bernard:36-2: Que faire\u2026 - Culminances\",\"isPartOf\":{\"@id\":\"https:\/\/www.masharif.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.masharif.com\/fr\/2019\/05\/20\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-36-poemes-de-france-bernard36-2-faire\/#primaryimage\"},\"datePublished\":\"2019-05-20T08:27:56+00:00\",\"dateModified\":\"2019-05-20T08:27:56+00:00\",\"author\":{\"@id\":\"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/839a7026efe9fa825134097c1041e4a0\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.masharif.com\/fr\/2019\/05\/20\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-36-poemes-de-france-bernard36-2-faire\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.masharif.com\/fr\/2019\/05\/20\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-36-poemes-de-france-bernard36-2-faire\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.masharif.com\/fr\/2019\/05\/20\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-36-poemes-de-france-bernard36-2-faire\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.masharif.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor :36\u2013Les po\u00e8mes de France Bernard:36-2: Que faire\u2026\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/839a7026efe9fa825134097c1041e4a0\",\"name\":\"Mohamed Salah Ben Amor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f64806401ad5ed604ffec2272b19ef46?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f64806401ad5ed604ffec2272b19ef46?s=96&d=identicon&r=g\",\"caption\":\"Mohamed Salah Ben Amor\"},\"sameAs\":[\"http:\/\/ben-amor.info\"],\"url\":\"https:\/\/www.masharif.com\/fr\/author\/msba\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor :36\u2013Les po\u00e8mes de France Bernard:36-2: Que faire\u2026 - Culminances","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.masharif.com\/fr\/2019\/05\/20\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-36-poemes-de-france-bernard36-2-faire\/","og_locale":"fr_FR","og_type":"article","og_title":"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor :36\u2013Les po\u00e8mes de France Bernard:36-2: Que faire\u2026 - Culminances","og_description":"&nbsp; Quand je\u00a0me mure dans l\u2019inaction Quand\u00a0la vie du dehors\u00a0m\u2019inonde Quand\u00a0je ne peux plus respirer le monde Quand mon\u00a0c\u0153ur bat dans la pulpe de mes mains Quand ma\u00a0musique perd ses partitions Je passe des heures au piano Tapotant sur\u00a0le d\u00e9saccord des touches J\u2019\u00e9tudie les sonates de l\u2019amour La musique classique s\u2019est \u00e9teinte Le clavier d\u2019ivoire ...","og_url":"https:\/\/www.masharif.com\/fr\/2019\/05\/20\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-36-poemes-de-france-bernard36-2-faire\/","og_site_name":"Culminances","article_published_time":"2019-05-20T08:27:56+00:00","og_image":[{"width":396,"height":396,"url":"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/05\/10405558_10202081649145177_2788907240823377239_n.jpg","type":"image\/jpeg"}],"author":"Mohamed Salah Ben Amor","twitter_card":"summary","twitter_misc":{"\u00c9crit par":"Mohamed Salah Ben Amor","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.masharif.com\/fr\/#website","url":"https:\/\/www.masharif.com\/fr\/","name":"Culminances","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.masharif.com\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.masharif.com\/fr\/2019\/05\/20\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-36-poemes-de-france-bernard36-2-faire\/#primaryimage","url":"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/05\/10405558_10202081649145177_2788907240823377239_n.jpg","contentUrl":"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/05\/10405558_10202081649145177_2788907240823377239_n.jpg","width":396,"height":396},{"@type":"WebPage","@id":"https:\/\/www.masharif.com\/fr\/2019\/05\/20\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-36-poemes-de-france-bernard36-2-faire\/","url":"https:\/\/www.masharif.com\/fr\/2019\/05\/20\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-36-poemes-de-france-bernard36-2-faire\/","name":"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor :36\u2013Les po\u00e8mes de France Bernard:36-2: Que faire\u2026 - Culminances","isPartOf":{"@id":"https:\/\/www.masharif.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.masharif.com\/fr\/2019\/05\/20\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-36-poemes-de-france-bernard36-2-faire\/#primaryimage"},"datePublished":"2019-05-20T08:27:56+00:00","dateModified":"2019-05-20T08:27:56+00:00","author":{"@id":"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/839a7026efe9fa825134097c1041e4a0"},"breadcrumb":{"@id":"https:\/\/www.masharif.com\/fr\/2019\/05\/20\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-36-poemes-de-france-bernard36-2-faire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.masharif.com\/fr\/2019\/05\/20\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-36-poemes-de-france-bernard36-2-faire\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.masharif.com\/fr\/2019\/05\/20\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-36-poemes-de-france-bernard36-2-faire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.masharif.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor :36\u2013Les po\u00e8mes de France Bernard:36-2: Que faire\u2026"}]},{"@type":"Person","@id":"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/839a7026efe9fa825134097c1041e4a0","name":"Mohamed Salah Ben Amor","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f64806401ad5ed604ffec2272b19ef46?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f64806401ad5ed604ffec2272b19ef46?s=96&d=identicon&r=g","caption":"Mohamed Salah Ben Amor"},"sameAs":["http:\/\/ben-amor.info"],"url":"https:\/\/www.masharif.com\/fr\/author\/msba\/"}]}},"_links":{"self":[{"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/posts\/9979"}],"collection":[{"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/comments?post=9979"}],"version-history":[{"count":1,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/posts\/9979\/revisions"}],"predecessor-version":[{"id":9981,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/posts\/9979\/revisions\/9981"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/media\/9969"}],"wp:attachment":[{"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/media?parent=9979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/categories?post=9979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/tags?post=9979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}