{"id":9813,"date":"2019-04-15T08:26:26","date_gmt":"2019-04-15T07:26:26","guid":{"rendered":"http:\/\/www.masharif.com\/fr\/?p=9813"},"modified":"2019-04-15T08:27:02","modified_gmt":"2019-04-15T07:27:02","slug":"archives-commentaires-poetiques-de-mohamed-salah-ben-amor-30-poemes-de-rachel-chidiac-30-4-courroux","status":"publish","type":"post","link":"https:\/\/www.masharif.com\/fr\/2019\/04\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-30-poemes-de-rachel-chidiac-30-4-courroux\/","title":{"rendered":"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor :30\u2013Les po\u00e8mes de Rachel Chidiac : 30-4 : Courroux"},"content":{"rendered":"<div id=\"attachment_9253\" style=\"width: 221px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/12\/18239_10200150462473778_758128806_n.jpg\"><img aria-describedby=\"caption-attachment-9253\" loading=\"lazy\" class=\"wp-image-9253 size-medium\" src=\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/12\/18239_10200150462473778_758128806_n-211x300.jpg\" alt=\"\" width=\"211\" height=\"300\" srcset=\"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/12\/18239_10200150462473778_758128806_n-211x300.jpg 211w, https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/12\/18239_10200150462473778_758128806_n.jpg 287w\" sizes=\"(max-width: 211px) 100vw, 211px\" \/><\/a><p id=\"caption-attachment-9253\" class=\"wp-caption-text\">Rachel Chidiac<\/p><\/div>\n<p><a href=\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/04\/1500825_10201203260866838_1017728114_o.jpg\"><img loading=\"lazy\" class=\"alignnone size-medium wp-image-9814\" src=\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/04\/1500825_10201203260866838_1017728114_o-300x208.jpg\" alt=\"\" width=\"300\" height=\"208\" srcset=\"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/04\/1500825_10201203260866838_1017728114_o-300x208.jpg 300w, https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/04\/1500825_10201203260866838_1017728114_o-768x531.jpg 768w, https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/04\/1500825_10201203260866838_1017728114_o-1024x708.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Courroux \u00d6 d\u00e9cembre !<\/strong><\/p>\n<p><strong>Souffle !<\/strong><\/p>\n<p><strong>Voici le froid qui point<\/strong><\/p>\n<p><strong>Sur le front des sentiers<\/strong><\/p>\n<p><strong>\u00d6 tonnerre gronde !<\/strong><\/p>\n<p><strong>\u00a0Ne crois pas que le printemps<\/strong><\/p>\n<p><strong>\u00a0Est le spectre du cr\u00e9puscule<\/strong><\/p>\n<p><strong>Ce sont des broussailles de roses<\/strong><\/p>\n<p><strong>Qui ont fan\u00e9<\/strong><\/p>\n<p><strong>Ce sont les l\u00e8vres de l\u2019aube<\/strong><\/p>\n<p><strong>Qui se sont tues<\/strong><\/p>\n<p><strong>L\u2019envie n\u2019est point un culte<\/strong><\/p>\n<p><strong>Le culte n\u2019est nullement une passion<\/strong><\/p>\n<p><strong>Et la passion, non plus, n\u2019est pas<\/strong><\/p>\n<p><strong>Une fleur qui rend la vie aux c\u0153urs<\/strong><\/p>\n<p><strong>Pr\u00e9pare tes valises \u00f4 Temps<\/strong><\/p>\n<p><strong>Rassemble les r\u00eaves<\/strong><\/p>\n<p><strong>Qui ont somnol\u00e9 dans ta trousse<\/strong><\/p>\n<p><strong>Et fuis<\/strong><\/p>\n<p><strong>Sans t\u2019enqu\u00e9rir<\/strong><\/p>\n<p><strong>\u00a0Sur la mort des ruisseaux<\/strong><\/p>\n<p><strong>Sur des brandons mis\u00e9rables<\/strong><\/p>\n<p><strong>Sans t\u2019enqu\u00e9rir<\/strong><\/p>\n<p><strong>Sur la solitude attristante des oiseaux<\/strong><\/p>\n<p><strong>Sur l\u2019\u00e9gorgement d\u2019un homme pieux<\/strong><\/p>\n<p><strong>C\u2019est l\u2018amour qui est devenu<\/strong><\/p>\n<p><strong>Aussi aveuglant que le kh\u00f4l<\/strong><\/p>\n<p><strong>C\u2019est l\u2019\u00e2me qui est une monture<\/strong><\/p>\n<p><strong>Pour une \u00e9ternit\u00e9 sans sel<\/strong><\/p>\n<p><strong>Qui dure infiniment<\/strong><\/p>\n<p><strong>Fuis \u00f4 Temps !<\/strong><\/p>\n<p><strong>Ne pose aucune question !<\/strong><\/p>\n<p><strong>Et laisse la gloire<\/strong><\/p>\n<p><strong>A celui qui a r\u00e9ussi<\/strong><\/p>\n<p><strong>L\u2019h\u00e9ro\u00efque exploit<\/strong><\/p>\n<p><strong>De te briser !<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Presque sp\u00e9cialis\u00e9e dans le th\u00e8me amoureux et tout particuli\u00e8rement\u00a0 le sous-th\u00e8me de l\u2019amour platonique \u00e0 teneur orientale authentique\u00a0 qui se caract\u00e9rise par la fusion totale entre les deux \u00eatres qui s\u2019aiment ,\u00a0 aussi bien spirituellement\u00a0 que corporellement\u00a0 , sur terre\u00a0 puis dans l\u2019au-del\u00e0 , l\u2019auteure de ce po\u00e8me se penche cette fois sur un autre th\u00e8me qui ne lui est \u00a0pas , en v\u00e9rit\u00e9, totalement \u00e9tranger, celui de la nature , \u00e9tant donn\u00e9 qu\u2019elle est habitu\u00e9e \u00e0 aborder le sujet de l\u2019amour sous un arri\u00e8re- fond romantique .N\u00e9anmoins ,le sujet de ce po\u00e8me \u00a0\u00a0para\u00eet \u00eatre inspir\u00e9 du moment pr\u00e9sent , du fait que le discours de la po\u00e9tesse y est adress\u00e9 \u00e0 \u00a0d\u00e9cembre. Et le motif de ce choix est , semble-t-il , spontan\u00e9\u00a0:l\u2019\u00e9tat \u00e9motionnel\u00a0 particulier que ce mois suscite naturellement chez les \u00e2mes hypersensibles \u00a0et en premier lieu celles des po\u00e8tes .En effet, la locutrice s\u2019\u00e9lance , d\u00e8s le d\u00e9but, dans un discours col\u00e9rique \u00e0 l\u2019\u00e9gard de cette p\u00e9riode de l\u2019ann\u00e9e qui se situe entre la fin de l\u2019automne et le d\u00e9but de l\u2019hiver et au cours de laquelle la nature perd toute sa vivacit\u00e9 et se retrouve \u00a0d\u00e9nud\u00e9e, appauvrie et affaiblie <strong>(ce sont des broussailles de roses qui ont fan\u00e9- \u00a0ce sont les <\/strong>l\u00e8vres de l\u2019aube \u00a0qui se sont tues &#8211; mort des ruisseaux &#8211; brandons mis\u00e9rables \u2013 solitude attristante des oiseaux ).Mais apr\u00e8s \u00a0avoir d\u00e9charg\u00e9\u00a0 son courroux contre\u00a0 ce cadre temporel relativement restreint ( d\u00e9cembre ) , elle s\u2019en prend violemment contre sa source-m\u00e8re\u00a0:Le Temps , passant ,de ce fait, du simple ton romantique au ton existentiel et s\u2019offrant un contexte propice \u00e0 la r\u00e9flexion philosophique sur \u00a0les fluctuations de l\u2019\u00e2me humaine et sa condition dans l\u2019univers (<strong>l\u2019envie n\u2019est point un culte \u00a0&#8211; le culte n\u2019est nullement une passion &#8211; et la passion, non plus, n\u2019est pas une fleur qui rend la vie aux c\u0153urs &#8211; c\u2019est l\u2019\u00e2me qui est une monture pour une \u00e9ternit\u00e9 sans sel \u00a0qui dure infiniment \u00a0<\/strong>\u00a0).<\/p>\n<p>C\u00f4t\u00e9 style, la po\u00e9tesse , forte de sa sensibilit\u00e9 esth\u00e9tique aiguis\u00e9e , nous a gratifi\u00e9s , du d\u00e9but du po\u00e8me jusqu\u2019\u00e0 sa fin , d\u2019une s\u00e9rie d\u2019images attrayantes \u00e9voquant un m\u00e9lange de m\u00e9lancolie et de col\u00e8re .<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Courroux \u00d6 d\u00e9cembre ! Souffle ! Voici le froid qui point Sur le front des sentiers \u00d6 tonnerre gronde ! \u00a0Ne crois pas que le printemps \u00a0Est le spectre du cr\u00e9puscule Ce sont des broussailles de roses Qui ont fan\u00e9 Ce sont les l\u00e8vres de l\u2019aube Qui se sont tues L\u2019envie n\u2019est point un &#8230;<\/p>\n","protected":false},"author":2,"featured_media":9253,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor :30\u2013Les po\u00e8mes de Rachel Chidiac : 30-4 : Courroux - Culminances<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.masharif.com\/fr\/2019\/04\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-30-poemes-de-rachel-chidiac-30-4-courroux\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor :30\u2013Les po\u00e8mes de Rachel Chidiac : 30-4 : Courroux - Culminances\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Courroux \u00d6 d\u00e9cembre ! Souffle ! Voici le froid qui point Sur le front des sentiers \u00d6 tonnerre gronde ! \u00a0Ne crois pas que le printemps \u00a0Est le spectre du cr\u00e9puscule Ce sont des broussailles de roses Qui ont fan\u00e9 Ce sont les l\u00e8vres de l\u2019aube Qui se sont tues L\u2019envie n\u2019est point un ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.masharif.com\/fr\/2019\/04\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-30-poemes-de-rachel-chidiac-30-4-courroux\/\" \/>\n<meta property=\"og:site_name\" content=\"Culminances\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-15T07:26:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-15T07:27:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/12\/18239_10200150462473778_758128806_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"287\" \/>\n\t<meta property=\"og:image:height\" content=\"408\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mohamed Salah Ben Amor\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mohamed Salah Ben Amor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.masharif.com\/fr\/#website\",\"url\":\"https:\/\/www.masharif.com\/fr\/\",\"name\":\"Culminances\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.masharif.com\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.masharif.com\/fr\/2019\/04\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-30-poemes-de-rachel-chidiac-30-4-courroux\/#primaryimage\",\"url\":\"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/12\/18239_10200150462473778_758128806_n.jpg\",\"contentUrl\":\"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/12\/18239_10200150462473778_758128806_n.jpg\",\"width\":287,\"height\":408},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.masharif.com\/fr\/2019\/04\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-30-poemes-de-rachel-chidiac-30-4-courroux\/\",\"url\":\"https:\/\/www.masharif.com\/fr\/2019\/04\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-30-poemes-de-rachel-chidiac-30-4-courroux\/\",\"name\":\"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor :30\u2013Les po\u00e8mes de Rachel Chidiac : 30-4 : Courroux - Culminances\",\"isPartOf\":{\"@id\":\"https:\/\/www.masharif.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.masharif.com\/fr\/2019\/04\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-30-poemes-de-rachel-chidiac-30-4-courroux\/#primaryimage\"},\"datePublished\":\"2019-04-15T07:26:26+00:00\",\"dateModified\":\"2019-04-15T07:27:02+00:00\",\"author\":{\"@id\":\"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/839a7026efe9fa825134097c1041e4a0\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.masharif.com\/fr\/2019\/04\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-30-poemes-de-rachel-chidiac-30-4-courroux\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.masharif.com\/fr\/2019\/04\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-30-poemes-de-rachel-chidiac-30-4-courroux\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.masharif.com\/fr\/2019\/04\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-30-poemes-de-rachel-chidiac-30-4-courroux\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.masharif.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor :30\u2013Les po\u00e8mes de Rachel Chidiac : 30-4 : Courroux\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/839a7026efe9fa825134097c1041e4a0\",\"name\":\"Mohamed Salah Ben Amor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f64806401ad5ed604ffec2272b19ef46?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f64806401ad5ed604ffec2272b19ef46?s=96&d=identicon&r=g\",\"caption\":\"Mohamed Salah Ben Amor\"},\"sameAs\":[\"http:\/\/ben-amor.info\"],\"url\":\"https:\/\/www.masharif.com\/fr\/author\/msba\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor :30\u2013Les po\u00e8mes de Rachel Chidiac : 30-4 : Courroux - Culminances","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.masharif.com\/fr\/2019\/04\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-30-poemes-de-rachel-chidiac-30-4-courroux\/","og_locale":"fr_FR","og_type":"article","og_title":"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor :30\u2013Les po\u00e8mes de Rachel Chidiac : 30-4 : Courroux - Culminances","og_description":"&nbsp; Courroux \u00d6 d\u00e9cembre ! Souffle ! Voici le froid qui point Sur le front des sentiers \u00d6 tonnerre gronde ! \u00a0Ne crois pas que le printemps \u00a0Est le spectre du cr\u00e9puscule Ce sont des broussailles de roses Qui ont fan\u00e9 Ce sont les l\u00e8vres de l\u2019aube Qui se sont tues L\u2019envie n\u2019est point un ...","og_url":"https:\/\/www.masharif.com\/fr\/2019\/04\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-30-poemes-de-rachel-chidiac-30-4-courroux\/","og_site_name":"Culminances","article_published_time":"2019-04-15T07:26:26+00:00","article_modified_time":"2019-04-15T07:27:02+00:00","og_image":[{"width":287,"height":408,"url":"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/12\/18239_10200150462473778_758128806_n.jpg","type":"image\/jpeg"}],"author":"Mohamed Salah Ben Amor","twitter_card":"summary","twitter_misc":{"\u00c9crit par":"Mohamed Salah Ben Amor","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.masharif.com\/fr\/#website","url":"https:\/\/www.masharif.com\/fr\/","name":"Culminances","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.masharif.com\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.masharif.com\/fr\/2019\/04\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-30-poemes-de-rachel-chidiac-30-4-courroux\/#primaryimage","url":"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/12\/18239_10200150462473778_758128806_n.jpg","contentUrl":"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/12\/18239_10200150462473778_758128806_n.jpg","width":287,"height":408},{"@type":"WebPage","@id":"https:\/\/www.masharif.com\/fr\/2019\/04\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-30-poemes-de-rachel-chidiac-30-4-courroux\/","url":"https:\/\/www.masharif.com\/fr\/2019\/04\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-30-poemes-de-rachel-chidiac-30-4-courroux\/","name":"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor :30\u2013Les po\u00e8mes de Rachel Chidiac : 30-4 : Courroux - Culminances","isPartOf":{"@id":"https:\/\/www.masharif.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.masharif.com\/fr\/2019\/04\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-30-poemes-de-rachel-chidiac-30-4-courroux\/#primaryimage"},"datePublished":"2019-04-15T07:26:26+00:00","dateModified":"2019-04-15T07:27:02+00:00","author":{"@id":"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/839a7026efe9fa825134097c1041e4a0"},"breadcrumb":{"@id":"https:\/\/www.masharif.com\/fr\/2019\/04\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-30-poemes-de-rachel-chidiac-30-4-courroux\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.masharif.com\/fr\/2019\/04\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-30-poemes-de-rachel-chidiac-30-4-courroux\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.masharif.com\/fr\/2019\/04\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-30-poemes-de-rachel-chidiac-30-4-courroux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.masharif.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor :30\u2013Les po\u00e8mes de Rachel Chidiac : 30-4 : Courroux"}]},{"@type":"Person","@id":"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/839a7026efe9fa825134097c1041e4a0","name":"Mohamed Salah Ben Amor","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f64806401ad5ed604ffec2272b19ef46?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f64806401ad5ed604ffec2272b19ef46?s=96&d=identicon&r=g","caption":"Mohamed Salah Ben Amor"},"sameAs":["http:\/\/ben-amor.info"],"url":"https:\/\/www.masharif.com\/fr\/author\/msba\/"}]}},"_links":{"self":[{"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/posts\/9813"}],"collection":[{"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/comments?post=9813"}],"version-history":[{"count":2,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/posts\/9813\/revisions"}],"predecessor-version":[{"id":9816,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/posts\/9813\/revisions\/9816"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/media\/9253"}],"wp:attachment":[{"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/media?parent=9813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/categories?post=9813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/tags?post=9813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}