{"id":9779,"date":"2019-04-09T09:29:15","date_gmt":"2019-04-09T08:29:15","guid":{"rendered":"http:\/\/www.masharif.com\/fr\/?p=9779"},"modified":"2019-04-09T09:29:15","modified_gmt":"2019-04-09T08:29:15","slug":"archives-commentaires-poetiques-de-mohamed-salah-ben-amor-29-poemes-duo-delena-martinez-mohammed-el-qoch-26-4-revelations","status":"publish","type":"post","link":"https:\/\/www.masharif.com\/fr\/2019\/04\/09\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-29-poemes-duo-delena-martinez-mohammed-el-qoch-26-4-revelations\/","title":{"rendered":"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor : 29\u2013Les po\u00e8mes en duo d\u2019Elena Martinez et Mohammed El Qoch: 26 -4: R\u00e9v\u00e9lations&#8230;!"},"content":{"rendered":"<div id=\"attachment_9747\" style=\"width: 310px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/04\/53110768_333516130612714_4112335807581257728_n.jpg\"><img aria-describedby=\"caption-attachment-9747\" loading=\"lazy\" class=\"wp-image-9747 size-medium\" src=\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/04\/53110768_333516130612714_4112335807581257728_n-300x150.jpg\" alt=\"\" width=\"300\" height=\"150\" srcset=\"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/04\/53110768_333516130612714_4112335807581257728_n-300x150.jpg 300w, https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/04\/53110768_333516130612714_4112335807581257728_n.jpg 638w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-9747\" class=\"wp-caption-text\">Elena Martinez et Mohammed El Qoch<\/p><\/div>\n<p><a href=\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/04\/woman-1072237_960_720.jpg\"><img loading=\"lazy\" class=\"alignnone size-medium wp-image-9780\" src=\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/04\/woman-1072237_960_720-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/04\/woman-1072237_960_720-300x200.jpg 300w, https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/04\/woman-1072237_960_720-768x511.jpg 768w, https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/04\/woman-1072237_960_720.jpg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>J&#8217;ai aim\u00e9 cette brusque et\u00a0l\u00e9g\u00e8re bruine\u00a0\u00a0<\/strong><\/p>\n<p><strong>Qui mouilla nos t\u00eates, ce jour l\u00e0,<\/strong><\/p>\n<p><strong>Des \u00e9paules, aux pieds<\/strong><\/p>\n<p><strong>Le firmament jaloux<\/strong><\/p>\n<p><strong>Scruta nos pas et nous inonda\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>J&#8217;ai aim\u00e9 les vieux murs blancs<\/strong><\/p>\n<p><strong>O\u00f9 nous avons inscrits<\/strong><\/p>\n<p><strong>Deux mots et qui n&#8217;ont plus<\/strong><\/p>\n<p><strong>Qu&#8217;un morceau de ciel pour toiture<\/strong><\/p>\n<p><strong>Et qui, par les ronces mordues,<\/strong><\/p>\n<p><strong>Souffrent en silence pour dissimuler\u00a0<\/strong><\/p>\n<p><strong>Leurs blessures rid\u00e9es<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>J&#8217;ai aim\u00e9 les fleurs dans ce recueil imag\u00e9<\/strong><\/p>\n<p><strong>Cahier fleuri de ma grand-m\u00e8re,<\/strong><\/p>\n<p><strong>O\u00f9 son r\u00eave \u00e9tait prisonnier<\/strong><\/p>\n<p><strong>Pr\u00e8s\u00a0du portrait d&#8217;un militaire souriant<\/strong><\/p>\n<p><strong>A l&#8217;allure \u00e9l\u00e9gante des vieux soldats<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>J&#8217;ai aim\u00e9\u00a0ce sourire qui \u00e9tincela ma vie<\/strong><\/p>\n<p><strong>Ma d\u00e9chirure b\u00e9ante, ma plaie,<\/strong><\/p>\n<p><strong>Sur ces cils, j&#8217;ai vu mon devenir,<\/strong><\/p>\n<p><strong>Le chemin qui menait aux songes<\/strong><\/p>\n<p><strong>Nul besoin de phare, ses yeux,<\/strong><\/p>\n<p><strong>L&#8217;\u00e9meraude scintille<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>J&#8217;ai aim\u00e9 les choses du pass\u00e9 lointain<\/strong><\/p>\n<p><strong>Ces rires au clair des chandelles<\/strong><\/p>\n<p><strong>Ces longues veill\u00e9es nocturnes\u00a0<\/strong><\/p>\n<p><strong>J&#8217;ai aim\u00e9 les lieux charg\u00e9s d&#8217;histoire<\/strong><\/p>\n<p><strong>Me rappelant les pr\u00e9noms effac\u00e9s\u00a0<\/strong><\/p>\n<p><strong>Les pages de la m\u00e9moire<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>J&#8217;ai senti l&#8217;\u00e9treinte et la caresse immobiles<\/strong><\/p>\n<p><strong>\u00a0Des ombres des r\u00e9miniscences<\/strong><\/p>\n<p><strong>\u00a0J&#8217;ai ferm\u00e9 les yeux que tes halos submergent\u00a0<\/strong><\/p>\n<p><strong>\u00a0J&#8217;ai repris le poids de ma vie<\/strong><\/p>\n<p><strong>\u00a0Ma nuit jouit sous l&#8217;\u00e9toile des cieux<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Revoil\u00e0 le talentueux duo qui s\u2019unit et se s\u00e9pare selon les lois \u00a0intrins\u00e8ques de \u00a0l\u2019inspiration qui \u00a0est parfois collective \u00a0\u00a0et rev\u00eat parfois un caract\u00e8re \u00a0strictement individuel .Et entre ces va-et-vient, \u00a0\u00a0il nous laisse quelques fois\u00a0 une longue p\u00e9riode \u00a0sur notre faim .Dans ce nouveau po\u00e8me \u00e0 quatre pattes , le duo donne une le\u00e7on remarquable \u00e0 ceux qui confondent \u00a0l\u2019amour en tant que sentiment que des centaines de millions de personnes peuvent \u00e9prouver et la po\u00e9sie amoureuse qui est avant tout un art \u00a0et exige \u00a0donc du talent\u00a0 dont ne jouit qu\u2019une cat\u00e9gorie bien restreinte de dou\u00e9s \u00a0Et la preuve en est \u00a0ces images de pure cr\u00e9ation que leur imagination et leur sensibilit\u00e9 esth\u00e9tique ont con\u00e7ues . Est-il \u00a0, en effet , \u00e0 la port\u00e9e de n\u2019importe qui \u00a0de se repr\u00e9senter cette jalousie vengeresse du ciel qui \u00a0le pousse \u00e0 d\u00e9verser sa pluie \u00a0sur les deux tourtereaux\u00a0? \u00a0Ou cette nostalgie\u00a0 \u00e9mouvante qui se d\u00e9gage \u00a0de la deuxi\u00e8me \u00a0\u00a0et la troisi\u00e8me \u00a0strophes o\u00f9 est projet\u00e9 l\u2019\u00e9tat d\u2019\u00e2me douloureux \u00a0de la locutrice et du locuteur\u00a0: \u00a0d\u2019abord sur un vieux mur sans plafond \u00a0au long duquel \u00a0ont grimp\u00e9 des ronces mordues\u00a0 , \u00a0ensuite sur le recueil imag\u00e9 \u00a0d\u2019une grand-m\u00e8re qui \u00a0revit \u00a0avec tant de peine et de regret ses souvenirs de jeunesse \u00e0 jamais r\u00e9volus\u00a0? Ou cette fine interception du devenir \u00a0personnel dans les cils \u00a0et les yeux du bien-aim\u00e9 assimil\u00e9s \u00e0 des \u00e9meraudes\u00a0?\u00a0 Ou cette fuite en arri\u00e8re vers l\u2019ambiance chaleureuse \u00a0et joyeuse des veill\u00e9es nocturnes afin \u00a0\u00a0de s\u2019y ressourcer \u00a0les forces morales n\u00e9cessaires \u00e0\u00a0 vaincre la m\u00e9lancolie du pr\u00e9sent\u00a0? Voila ce qu\u2019on appelle po\u00e9sie amoureuse et non cette d\u00e9flagration de sentiments bruts trait\u00e9s\u00a0 artificiellement\u00a0 au moyen d\u2019une versification compass\u00e9e.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; J&#8217;ai aim\u00e9 cette brusque et\u00a0l\u00e9g\u00e8re bruine\u00a0\u00a0 Qui mouilla nos t\u00eates, ce jour l\u00e0, Des \u00e9paules, aux pieds Le firmament jaloux Scruta nos pas et nous inonda\u00a0 \u00a0 J&#8217;ai aim\u00e9 les vieux murs blancs O\u00f9 nous avons inscrits Deux mots et qui n&#8217;ont plus Qu&#8217;un morceau de ciel pour toiture Et qui, par les ronces &#8230;<\/p>\n","protected":false},"author":2,"featured_media":9747,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor : 29\u2013Les po\u00e8mes en duo d\u2019Elena Martinez et Mohammed El Qoch: 26 -4: R\u00e9v\u00e9lations...! - Culminances<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.masharif.com\/fr\/2019\/04\/09\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-29-poemes-duo-delena-martinez-mohammed-el-qoch-26-4-revelations\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor : 29\u2013Les po\u00e8mes en duo d\u2019Elena Martinez et Mohammed El Qoch: 26 -4: R\u00e9v\u00e9lations...! - Culminances\" \/>\n<meta property=\"og:description\" content=\"&nbsp; J&#8217;ai aim\u00e9 cette brusque et\u00a0l\u00e9g\u00e8re bruine\u00a0\u00a0 Qui mouilla nos t\u00eates, ce jour l\u00e0, Des \u00e9paules, aux pieds Le firmament jaloux Scruta nos pas et nous inonda\u00a0 \u00a0 J&#8217;ai aim\u00e9 les vieux murs blancs O\u00f9 nous avons inscrits Deux mots et qui n&#8217;ont plus Qu&#8217;un morceau de ciel pour toiture Et qui, par les ronces ...\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.masharif.com\/fr\/2019\/04\/09\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-29-poemes-duo-delena-martinez-mohammed-el-qoch-26-4-revelations\/\" \/>\n<meta property=\"og:site_name\" content=\"Culminances\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-09T08:29:15+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/04\/53110768_333516130612714_4112335807581257728_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"638\" \/>\n\t<meta property=\"og:image:height\" content=\"318\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mohamed Salah Ben Amor\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mohamed Salah Ben Amor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.masharif.com\/fr\/#website\",\"url\":\"https:\/\/www.masharif.com\/fr\/\",\"name\":\"Culminances\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.masharif.com\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\/\/www.masharif.com\/fr\/2019\/04\/09\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-29-poemes-duo-delena-martinez-mohammed-el-qoch-26-4-revelations\/#primaryimage\",\"url\":\"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/04\/53110768_333516130612714_4112335807581257728_n.jpg\",\"contentUrl\":\"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/04\/53110768_333516130612714_4112335807581257728_n.jpg\",\"width\":638,\"height\":318},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.masharif.com\/fr\/2019\/04\/09\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-29-poemes-duo-delena-martinez-mohammed-el-qoch-26-4-revelations\/\",\"url\":\"http:\/\/www.masharif.com\/fr\/2019\/04\/09\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-29-poemes-duo-delena-martinez-mohammed-el-qoch-26-4-revelations\/\",\"name\":\"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor : 29\u2013Les po\u00e8mes en duo d\u2019Elena Martinez et Mohammed El Qoch: 26 -4: R\u00e9v\u00e9lations...! - Culminances\",\"isPartOf\":{\"@id\":\"https:\/\/www.masharif.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.masharif.com\/fr\/2019\/04\/09\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-29-poemes-duo-delena-martinez-mohammed-el-qoch-26-4-revelations\/#primaryimage\"},\"datePublished\":\"2019-04-09T08:29:15+00:00\",\"dateModified\":\"2019-04-09T08:29:15+00:00\",\"author\":{\"@id\":\"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/839a7026efe9fa825134097c1041e4a0\"},\"breadcrumb\":{\"@id\":\"http:\/\/www.masharif.com\/fr\/2019\/04\/09\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-29-poemes-duo-delena-martinez-mohammed-el-qoch-26-4-revelations\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.masharif.com\/fr\/2019\/04\/09\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-29-poemes-duo-delena-martinez-mohammed-el-qoch-26-4-revelations\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.masharif.com\/fr\/2019\/04\/09\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-29-poemes-duo-delena-martinez-mohammed-el-qoch-26-4-revelations\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.masharif.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor : 29\u2013Les po\u00e8mes en duo d\u2019Elena Martinez et Mohammed El Qoch: 26 -4: R\u00e9v\u00e9lations&#8230;!\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/839a7026efe9fa825134097c1041e4a0\",\"name\":\"Mohamed Salah Ben Amor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f64806401ad5ed604ffec2272b19ef46?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f64806401ad5ed604ffec2272b19ef46?s=96&d=identicon&r=g\",\"caption\":\"Mohamed Salah Ben Amor\"},\"sameAs\":[\"http:\/\/ben-amor.info\"],\"url\":\"https:\/\/www.masharif.com\/fr\/author\/msba\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor : 29\u2013Les po\u00e8mes en duo d\u2019Elena Martinez et Mohammed El Qoch: 26 -4: R\u00e9v\u00e9lations...! - Culminances","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.masharif.com\/fr\/2019\/04\/09\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-29-poemes-duo-delena-martinez-mohammed-el-qoch-26-4-revelations\/","og_locale":"fr_FR","og_type":"article","og_title":"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor : 29\u2013Les po\u00e8mes en duo d\u2019Elena Martinez et Mohammed El Qoch: 26 -4: R\u00e9v\u00e9lations...! - Culminances","og_description":"&nbsp; J&#8217;ai aim\u00e9 cette brusque et\u00a0l\u00e9g\u00e8re bruine\u00a0\u00a0 Qui mouilla nos t\u00eates, ce jour l\u00e0, Des \u00e9paules, aux pieds Le firmament jaloux Scruta nos pas et nous inonda\u00a0 \u00a0 J&#8217;ai aim\u00e9 les vieux murs blancs O\u00f9 nous avons inscrits Deux mots et qui n&#8217;ont plus Qu&#8217;un morceau de ciel pour toiture Et qui, par les ronces ...","og_url":"http:\/\/www.masharif.com\/fr\/2019\/04\/09\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-29-poemes-duo-delena-martinez-mohammed-el-qoch-26-4-revelations\/","og_site_name":"Culminances","article_published_time":"2019-04-09T08:29:15+00:00","og_image":[{"width":638,"height":318,"url":"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/04\/53110768_333516130612714_4112335807581257728_n.jpg","type":"image\/jpeg"}],"author":"Mohamed Salah Ben Amor","twitter_card":"summary","twitter_misc":{"\u00c9crit par":"Mohamed Salah Ben Amor","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.masharif.com\/fr\/#website","url":"https:\/\/www.masharif.com\/fr\/","name":"Culminances","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.masharif.com\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/www.masharif.com\/fr\/2019\/04\/09\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-29-poemes-duo-delena-martinez-mohammed-el-qoch-26-4-revelations\/#primaryimage","url":"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/04\/53110768_333516130612714_4112335807581257728_n.jpg","contentUrl":"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/04\/53110768_333516130612714_4112335807581257728_n.jpg","width":638,"height":318},{"@type":"WebPage","@id":"http:\/\/www.masharif.com\/fr\/2019\/04\/09\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-29-poemes-duo-delena-martinez-mohammed-el-qoch-26-4-revelations\/","url":"http:\/\/www.masharif.com\/fr\/2019\/04\/09\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-29-poemes-duo-delena-martinez-mohammed-el-qoch-26-4-revelations\/","name":"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor : 29\u2013Les po\u00e8mes en duo d\u2019Elena Martinez et Mohammed El Qoch: 26 -4: R\u00e9v\u00e9lations...! - Culminances","isPartOf":{"@id":"https:\/\/www.masharif.com\/fr\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.masharif.com\/fr\/2019\/04\/09\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-29-poemes-duo-delena-martinez-mohammed-el-qoch-26-4-revelations\/#primaryimage"},"datePublished":"2019-04-09T08:29:15+00:00","dateModified":"2019-04-09T08:29:15+00:00","author":{"@id":"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/839a7026efe9fa825134097c1041e4a0"},"breadcrumb":{"@id":"http:\/\/www.masharif.com\/fr\/2019\/04\/09\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-29-poemes-duo-delena-martinez-mohammed-el-qoch-26-4-revelations\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.masharif.com\/fr\/2019\/04\/09\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-29-poemes-duo-delena-martinez-mohammed-el-qoch-26-4-revelations\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.masharif.com\/fr\/2019\/04\/09\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-29-poemes-duo-delena-martinez-mohammed-el-qoch-26-4-revelations\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.masharif.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor : 29\u2013Les po\u00e8mes en duo d\u2019Elena Martinez et Mohammed El Qoch: 26 -4: R\u00e9v\u00e9lations&#8230;!"}]},{"@type":"Person","@id":"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/839a7026efe9fa825134097c1041e4a0","name":"Mohamed Salah Ben Amor","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f64806401ad5ed604ffec2272b19ef46?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f64806401ad5ed604ffec2272b19ef46?s=96&d=identicon&r=g","caption":"Mohamed Salah Ben Amor"},"sameAs":["http:\/\/ben-amor.info"],"url":"https:\/\/www.masharif.com\/fr\/author\/msba\/"}]}},"_links":{"self":[{"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/posts\/9779"}],"collection":[{"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/comments?post=9779"}],"version-history":[{"count":1,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/posts\/9779\/revisions"}],"predecessor-version":[{"id":9781,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/posts\/9779\/revisions\/9781"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/media\/9747"}],"wp:attachment":[{"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/media?parent=9779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/categories?post=9779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/tags?post=9779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}