{"id":9522,"date":"2019-02-15T07:31:43","date_gmt":"2019-02-15T06:31:43","guid":{"rendered":"http:\/\/www.masharif.com\/fr\/?p=9522"},"modified":"2019-02-15T07:32:02","modified_gmt":"2019-02-15T06:32:02","slug":"archives-commentaires-poetiques-de-mohamed-salah-ben-amor-27-poemes-de-patricia-royet-27-4-a-lumiere-chandelles","status":"publish","type":"post","link":"https:\/\/www.masharif.com\/fr\/2019\/02\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-27-poemes-de-patricia-royet-27-4-a-lumiere-chandelles\/","title":{"rendered":"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor : 27\u2013Les po\u00e8mes de Patricia Royet :27-4 : A la lumi\u00e8re des chandelles"},"content":{"rendered":"<div id=\"attachment_9181\" style=\"width: 310px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/12\/47181217_754152568264871_7603980722709200896_n.jpg\"><img aria-describedby=\"caption-attachment-9181\" loading=\"lazy\" class=\"wp-image-9181 size-medium\" src=\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/12\/47181217_754152568264871_7603980722709200896_n-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/12\/47181217_754152568264871_7603980722709200896_n-300x300.jpg 300w, https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/12\/47181217_754152568264871_7603980722709200896_n-150x150.jpg 150w, https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/12\/47181217_754152568264871_7603980722709200896_n-55x55.jpg 55w, https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/12\/47181217_754152568264871_7603980722709200896_n.jpg 348w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-9181\" class=\"wp-caption-text\">Patricia Royet<\/p><\/div>\n<p><a href=\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/02\/lit-de-repos-non-valide-affiche-quatre-oreiller-tassel-malade-mourir-vieille-femme-detendue-paralyse-mort-lady-b7acnf.jpg\"><img loading=\"lazy\" class=\"alignnone size-medium wp-image-9523\" src=\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/02\/lit-de-repos-non-valide-affiche-quatre-oreiller-tassel-malade-mourir-vieille-femme-detendue-paralyse-mort-lady-b7acnf-300x281.jpg\" alt=\"\" width=\"300\" height=\"281\" srcset=\"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/02\/lit-de-repos-non-valide-affiche-quatre-oreiller-tassel-malade-mourir-vieille-femme-detendue-paralyse-mort-lady-b7acnf-300x281.jpg 300w, https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/02\/lit-de-repos-non-valide-affiche-quatre-oreiller-tassel-malade-mourir-vieille-femme-detendue-paralyse-mort-lady-b7acnf-768x720.jpg 768w, https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/02\/lit-de-repos-non-valide-affiche-quatre-oreiller-tassel-malade-mourir-vieille-femme-detendue-paralyse-mort-lady-b7acnf-1024x959.jpg 1024w, https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2019\/02\/lit-de-repos-non-valide-affiche-quatre-oreiller-tassel-malade-mourir-vieille-femme-detendue-paralyse-mort-lady-b7acnf.jpg 1300w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Dans la maison blanche,<br \/>\nQue chaque printemps nourrit,<br \/>\nEn senteurs et joliment fleurie,<br \/>\nLes roses pleurent,<br \/>\nLa po\u00e9sie d&#8217;une couleur,<br \/>\nEn ce dimanche matin,<br \/>\nPas de bleu,<br \/>\nPas de soleil,<br \/>\nLa triste brume a cach\u00e9,<br \/>\nLa douceur du ciel,<\/strong><\/p>\n<p><strong>Une flamme s&#8217;envole,<br \/>\nLa pluie se met \u00e0 tomber,<br \/>\nUne lumi\u00e8re s&#8217;\u00e9teint,<br \/>\nIl est dix heures vingt,<\/strong><\/p>\n<p><strong>Dans la chambre aux volets clos,<br \/>\nQuatre-vingt-deux ans de souvenirs retrouvent l&#8217;\u00e9ternel,<br \/>\nEn effleurant la poussi\u00e8re de vieux rideaux,<br \/>\nAllong\u00e9e sur le lit,<br \/>\nBelle \u00e2me en repos,<br \/>\nEclair\u00e9e par des chandelles,<br \/>\nMamie Louise s&#8217;est endormie,<br \/>\nDans sa main fragile,<br \/>\nUne photo jaunie,<br \/>\nContre sa poitrine,<br \/>\nLe sourire de Lucien,<br \/>\nPour l&#8217;\u00e9ternit\u00e9,<br \/>\nElle rejoint.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Voici un po\u00e8me qui s\u2019inscrit parfaitement dans la lign\u00e9e tragique, en r\u00e9unissant l\u2019Amour, l\u2019un des plus forts liens d\u2019attache \u00e0 ce bas-monde et la Mort qui est la n\u00e9gation m\u00eame de la vie .N\u00e9anmoins, cette dualit\u00e9, qui est dans son essence oppositive, se transforme, sous la plume de l\u2019auteure, en une occasion faste et prometteuse pour une victoire de l\u2019Amour sur la Mort , non sur terre mais dans l\u2019au-del\u00e0 .Et du coup , le cadre naturel triste que la po\u00e9tesse s\u2019est \u00e9vertu\u00e9, dans les quinze premiers vers, \u00e0 mettre en \u00e9vidence ,du fait qu\u2019il abrite une sc\u00e8ne mortuaire, s\u2019av\u00e8re n\u2019\u00eatre qu\u2019un simple subterfuge technique pour intensifier l\u2019effet de surprise finale que susciteront les pr\u00e9paratifs faits par la d\u00e9funte, avant de rendre l\u2019\u00e2me pour rencontrer son bien-aim\u00e9 qui l\u2019avait pr\u00e9c\u00e9d\u00e9e (<strong>Mamie Louise s&#8217;est endormie, dans sa main fragile, une photo jaunie, contre sa poitrine, le sourire de Lucien, pour l&#8217;\u00e9ternit\u00e9, elle rejoint<\/strong> ) , une surprise, qui rend la sc\u00e8ne, pour le lecteur croyant, moins tragique et lui conf\u00e8re une nouvelle dimension : celle de la fid\u00e9lit\u00e9 en amour .En plus de ce renversement inattendu de la situation d\u00e9crite, le po\u00e8me retient l\u2019attention par sa langue hautement po\u00e9tis\u00e9e gr\u00e2ce \u00e0 la texture m\u00e9taphorique dont il a \u00e9t\u00e9 dot\u00e9 surtout dans la description du cadre naturel qui laisse filtrer une sensibilit\u00e9 romantique effil\u00e9e et un talent r\u00e9el dans la personnification des \u00e9l\u00e9ments de la nature .<\/p>\n<p>Un autre po\u00e8me r\u00e9ussi de la part de cette charmeuse de muses qui ne finit pas de nous \u00e9tonner agr\u00e9ablement. Bravo Patricia et \u00e0 la prochaine !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Dans la maison blanche, Que chaque printemps nourrit, En senteurs et joliment fleurie, Les roses pleurent, La po\u00e9sie d&#8217;une couleur, En ce dimanche matin, Pas de bleu, Pas de soleil, La triste brume a cach\u00e9, La douceur du ciel, Une flamme s&#8217;envole, La pluie se met \u00e0 tomber, Une lumi\u00e8re s&#8217;\u00e9teint, Il est dix &#8230;<\/p>\n","protected":false},"author":2,"featured_media":9181,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor : 27\u2013Les po\u00e8mes de Patricia Royet :27-4 : A la lumi\u00e8re des chandelles - Culminances<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.masharif.com\/fr\/2019\/02\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-27-poemes-de-patricia-royet-27-4-a-lumiere-chandelles\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor : 27\u2013Les po\u00e8mes de Patricia Royet :27-4 : A la lumi\u00e8re des chandelles - Culminances\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Dans la maison blanche, Que chaque printemps nourrit, En senteurs et joliment fleurie, Les roses pleurent, La po\u00e9sie d&#8217;une couleur, En ce dimanche matin, Pas de bleu, Pas de soleil, La triste brume a cach\u00e9, La douceur du ciel, Une flamme s&#8217;envole, La pluie se met \u00e0 tomber, Une lumi\u00e8re s&#8217;\u00e9teint, Il est dix ...\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.masharif.com\/fr\/2019\/02\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-27-poemes-de-patricia-royet-27-4-a-lumiere-chandelles\/\" \/>\n<meta property=\"og:site_name\" content=\"Culminances\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-15T06:31:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-02-15T06:32:02+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/12\/47181217_754152568264871_7603980722709200896_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"348\" \/>\n\t<meta property=\"og:image:height\" content=\"348\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mohamed Salah Ben Amor\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mohamed Salah Ben Amor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.masharif.com\/fr\/#website\",\"url\":\"https:\/\/www.masharif.com\/fr\/\",\"name\":\"Culminances\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.masharif.com\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\/\/www.masharif.com\/fr\/2019\/02\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-27-poemes-de-patricia-royet-27-4-a-lumiere-chandelles\/#primaryimage\",\"url\":\"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/12\/47181217_754152568264871_7603980722709200896_n.jpg\",\"contentUrl\":\"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/12\/47181217_754152568264871_7603980722709200896_n.jpg\",\"width\":348,\"height\":348},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.masharif.com\/fr\/2019\/02\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-27-poemes-de-patricia-royet-27-4-a-lumiere-chandelles\/\",\"url\":\"http:\/\/www.masharif.com\/fr\/2019\/02\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-27-poemes-de-patricia-royet-27-4-a-lumiere-chandelles\/\",\"name\":\"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor : 27\u2013Les po\u00e8mes de Patricia Royet :27-4 : A la lumi\u00e8re des chandelles - Culminances\",\"isPartOf\":{\"@id\":\"https:\/\/www.masharif.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.masharif.com\/fr\/2019\/02\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-27-poemes-de-patricia-royet-27-4-a-lumiere-chandelles\/#primaryimage\"},\"datePublished\":\"2019-02-15T06:31:43+00:00\",\"dateModified\":\"2019-02-15T06:32:02+00:00\",\"author\":{\"@id\":\"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/839a7026efe9fa825134097c1041e4a0\"},\"breadcrumb\":{\"@id\":\"http:\/\/www.masharif.com\/fr\/2019\/02\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-27-poemes-de-patricia-royet-27-4-a-lumiere-chandelles\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.masharif.com\/fr\/2019\/02\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-27-poemes-de-patricia-royet-27-4-a-lumiere-chandelles\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.masharif.com\/fr\/2019\/02\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-27-poemes-de-patricia-royet-27-4-a-lumiere-chandelles\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.masharif.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor : 27\u2013Les po\u00e8mes de Patricia Royet :27-4 : A la lumi\u00e8re des chandelles\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/839a7026efe9fa825134097c1041e4a0\",\"name\":\"Mohamed Salah Ben Amor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f64806401ad5ed604ffec2272b19ef46?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f64806401ad5ed604ffec2272b19ef46?s=96&d=identicon&r=g\",\"caption\":\"Mohamed Salah Ben Amor\"},\"sameAs\":[\"http:\/\/ben-amor.info\"],\"url\":\"https:\/\/www.masharif.com\/fr\/author\/msba\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor : 27\u2013Les po\u00e8mes de Patricia Royet :27-4 : A la lumi\u00e8re des chandelles - Culminances","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.masharif.com\/fr\/2019\/02\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-27-poemes-de-patricia-royet-27-4-a-lumiere-chandelles\/","og_locale":"fr_FR","og_type":"article","og_title":"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor : 27\u2013Les po\u00e8mes de Patricia Royet :27-4 : A la lumi\u00e8re des chandelles - Culminances","og_description":"&nbsp; Dans la maison blanche, Que chaque printemps nourrit, En senteurs et joliment fleurie, Les roses pleurent, La po\u00e9sie d&#8217;une couleur, En ce dimanche matin, Pas de bleu, Pas de soleil, La triste brume a cach\u00e9, La douceur du ciel, Une flamme s&#8217;envole, La pluie se met \u00e0 tomber, Une lumi\u00e8re s&#8217;\u00e9teint, Il est dix ...","og_url":"http:\/\/www.masharif.com\/fr\/2019\/02\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-27-poemes-de-patricia-royet-27-4-a-lumiere-chandelles\/","og_site_name":"Culminances","article_published_time":"2019-02-15T06:31:43+00:00","article_modified_time":"2019-02-15T06:32:02+00:00","og_image":[{"width":348,"height":348,"url":"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/12\/47181217_754152568264871_7603980722709200896_n.jpg","type":"image\/jpeg"}],"author":"Mohamed Salah Ben Amor","twitter_card":"summary","twitter_misc":{"\u00c9crit par":"Mohamed Salah Ben Amor","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.masharif.com\/fr\/#website","url":"https:\/\/www.masharif.com\/fr\/","name":"Culminances","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.masharif.com\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/www.masharif.com\/fr\/2019\/02\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-27-poemes-de-patricia-royet-27-4-a-lumiere-chandelles\/#primaryimage","url":"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/12\/47181217_754152568264871_7603980722709200896_n.jpg","contentUrl":"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/12\/47181217_754152568264871_7603980722709200896_n.jpg","width":348,"height":348},{"@type":"WebPage","@id":"http:\/\/www.masharif.com\/fr\/2019\/02\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-27-poemes-de-patricia-royet-27-4-a-lumiere-chandelles\/","url":"http:\/\/www.masharif.com\/fr\/2019\/02\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-27-poemes-de-patricia-royet-27-4-a-lumiere-chandelles\/","name":"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor : 27\u2013Les po\u00e8mes de Patricia Royet :27-4 : A la lumi\u00e8re des chandelles - Culminances","isPartOf":{"@id":"https:\/\/www.masharif.com\/fr\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.masharif.com\/fr\/2019\/02\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-27-poemes-de-patricia-royet-27-4-a-lumiere-chandelles\/#primaryimage"},"datePublished":"2019-02-15T06:31:43+00:00","dateModified":"2019-02-15T06:32:02+00:00","author":{"@id":"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/839a7026efe9fa825134097c1041e4a0"},"breadcrumb":{"@id":"http:\/\/www.masharif.com\/fr\/2019\/02\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-27-poemes-de-patricia-royet-27-4-a-lumiere-chandelles\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.masharif.com\/fr\/2019\/02\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-27-poemes-de-patricia-royet-27-4-a-lumiere-chandelles\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.masharif.com\/fr\/2019\/02\/15\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-27-poemes-de-patricia-royet-27-4-a-lumiere-chandelles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.masharif.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor : 27\u2013Les po\u00e8mes de Patricia Royet :27-4 : A la lumi\u00e8re des chandelles"}]},{"@type":"Person","@id":"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/839a7026efe9fa825134097c1041e4a0","name":"Mohamed Salah Ben Amor","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f64806401ad5ed604ffec2272b19ef46?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f64806401ad5ed604ffec2272b19ef46?s=96&d=identicon&r=g","caption":"Mohamed Salah Ben Amor"},"sameAs":["http:\/\/ben-amor.info"],"url":"https:\/\/www.masharif.com\/fr\/author\/msba\/"}]}},"_links":{"self":[{"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/posts\/9522"}],"collection":[{"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/comments?post=9522"}],"version-history":[{"count":2,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/posts\/9522\/revisions"}],"predecessor-version":[{"id":9525,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/posts\/9522\/revisions\/9525"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/media\/9181"}],"wp:attachment":[{"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/media?parent=9522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/categories?post=9522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/tags?post=9522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}