{"id":8809,"date":"2018-09-17T14:42:33","date_gmt":"2018-09-17T13:42:33","guid":{"rendered":"http:\/\/www.masharif.com\/fr\/?p=8809"},"modified":"2018-09-17T14:42:33","modified_gmt":"2018-09-17T13:42:33","slug":"lamour-a-deserte-bleue-maissa-boutiche-alger-algerie","status":"publish","type":"post","link":"https:\/\/www.masharif.com\/fr\/2018\/09\/17\/lamour-a-deserte-bleue-maissa-boutiche-alger-algerie\/","title":{"rendered":"L\u2019amour a d\u00e9sert\u00e9 la bleue par :Maissa Boutiche \u2013 Alger &#8211; Alg\u00e9rie"},"content":{"rendered":"<div id=\"attachment_8175\" style=\"width: 200px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/05\/t\u00e9l\u00e9chargement-1.jpg\"><img aria-describedby=\"caption-attachment-8175\" loading=\"lazy\" class=\"wp-image-8175 size-full\" src=\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/05\/t\u00e9l\u00e9chargement-1.jpg\" alt=\"\" width=\"190\" height=\"265\" \/><\/a><p id=\"caption-attachment-8175\" class=\"wp-caption-text\">Maissa Boutiche<\/p><\/div>\n<p><a href=\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/09\/landscape-seaside-3406264_960_720.jpg\"><img loading=\"lazy\" class=\"alignnone size-medium wp-image-8810\" src=\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/09\/landscape-seaside-3406264_960_720-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/09\/landscape-seaside-3406264_960_720-300x200.jpg 300w, https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/09\/landscape-seaside-3406264_960_720-768x512.jpg 768w, https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/09\/landscape-seaside-3406264_960_720.jpg 960w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Tes vagues dansantes, hier, nous \u00e9gayaient<br \/>\nDans tes bras chauds, tu bordais nos r\u00eaves<br \/>\nEntre tes vagues, les sentiments se dandinaient<br \/>\nLe c\u0153ur palpitant, \u00a0monte la vague.<\/p>\n<p>Les r\u00eaves enfantaient et l\u2019espoir \u00e9tait l\u00e0<br \/>\nL\u2019amour enivrait \u00a0bon nombre de t\u00eates<br \/>\nBlessures \u00a0oubli\u00e9es<br \/>\nBleus estompaient<br \/>\nTous leurs maux noyaient dans le chant de tes vagues.<\/p>\n<p>Les amoureux ici et l\u00e0<br \/>\nSur tes belles c\u00f4tes, se promenaient<br \/>\nMain dans main, chantant la joie<br \/>\nSur ton sable humide, heureux<br \/>\nLes pens\u00e9es vaquent.<\/p>\n<p>Mais rien ne dure, ma belle bleue<br \/>\nRien ne demeure<br \/>\nL\u2019\u00e9t\u00e9 parti, l\u2019automne s\u2019installe<br \/>\nEt je vois ma belle bleue, de ma fen\u00eatre<br \/>\nQui contre le vent, se bat toute seule.<br \/>\nFrissonnantes, houleuses, ses hautes vagues<br \/>\nQui se jettent sur les quais et mettent bas<br \/>\nLes r\u00eaves d\u00e9chus ou oubli\u00e9s<br \/>\nAux mains de l\u2019usure du temps<br \/>\nO\u00f9 meurent les vagues.<\/p>\n<p>Ma bleue, tes yeux ont chang\u00e9 de couleur,<br \/>\nDevenus \u00a0gris, comme le ciel de l\u2019automne<br \/>\n\u00c9taient hier si beaux de leur bleu<br \/>\nOffraient la joie<br \/>\nOu nageaient les c\u0153urs et les \u00e2mes.<\/p>\n<p>Soleil timide en ce jour automnal<br \/>\nNuages lourds<br \/>\nAssombrissent le ciel, hier si beau.<br \/>\nL\u2019Automne est l\u00e0<br \/>\nLes r\u00eaves sommeillent<br \/>\nNon matinales<br \/>\nLes \u00a0plages d\u00e9sertes<br \/>\nMa bleue est l\u00e0, solitaire \u00e0 fondre l\u2019\u00e2me<br \/>\nSes criques et baies, d\u00e9sertes et nues<br \/>\nPlus d\u2019estivants, ni cris joyeux,<br \/>\nPlus d\u2019\u00e9clats<br \/>\nLes vagues sur les rocs, d\u00e9versent leurs larmes<br \/>\nSe jettent sur le lit humide, du sable.<\/p>\n<p>Rien ne dure, rien ne demeure<br \/>\nMa bleue Azur\u00a0!<br \/>\nSeules les mouettes et leurs pirouettes<br \/>\nSous ton ciel gris et vaste<br \/>\nPlus de r\u00eaves d\u2019\u00e9t\u00e9<br \/>\nPlus d\u2019\u00e9cho de la danse des pas.<br \/>\nSeul le silence se fait Ma\u00eetre des lieux<br \/>\nTout s\u2019est \u00e9vanoui \u00e0 la col\u00e8re de tes vagues<\/p>\n<p><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Tes vagues dansantes, hier, nous \u00e9gayaient Dans tes bras chauds, tu bordais nos r\u00eaves Entre tes vagues, les sentiments se dandinaient Le c\u0153ur palpitant, \u00a0monte la vague. Les r\u00eaves enfantaient et l\u2019espoir \u00e9tait l\u00e0 L\u2019amour enivrait \u00a0bon nombre de t\u00eates Blessures \u00a0oubli\u00e9es Bleus estompaient Tous leurs maux noyaient dans le chant de tes vagues. &#8230;<\/p>\n","protected":false},"author":2,"featured_media":8810,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L\u2019amour a d\u00e9sert\u00e9 la bleue par :Maissa Boutiche \u2013 Alger - Alg\u00e9rie - Culminances<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.masharif.com\/fr\/2018\/09\/17\/lamour-a-deserte-bleue-maissa-boutiche-alger-algerie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u2019amour a d\u00e9sert\u00e9 la bleue par :Maissa Boutiche \u2013 Alger - Alg\u00e9rie - Culminances\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Tes vagues dansantes, hier, nous \u00e9gayaient Dans tes bras chauds, tu bordais nos r\u00eaves Entre tes vagues, les sentiments se dandinaient Le c\u0153ur palpitant, \u00a0monte la vague. Les r\u00eaves enfantaient et l\u2019espoir \u00e9tait l\u00e0 L\u2019amour enivrait \u00a0bon nombre de t\u00eates Blessures \u00a0oubli\u00e9es Bleus estompaient Tous leurs maux noyaient dans le chant de tes vagues. ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.masharif.com\/fr\/2018\/09\/17\/lamour-a-deserte-bleue-maissa-boutiche-alger-algerie\/\" \/>\n<meta property=\"og:site_name\" content=\"Culminances\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-17T13:42:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/09\/landscape-seaside-3406264_960_720.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mohamed Salah Ben Amor\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mohamed Salah Ben Amor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.masharif.com\/fr\/#website\",\"url\":\"https:\/\/www.masharif.com\/fr\/\",\"name\":\"Culminances\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.masharif.com\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.masharif.com\/fr\/2018\/09\/17\/lamour-a-deserte-bleue-maissa-boutiche-alger-algerie\/#primaryimage\",\"url\":\"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/09\/landscape-seaside-3406264_960_720.jpg\",\"contentUrl\":\"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/09\/landscape-seaside-3406264_960_720.jpg\",\"width\":960,\"height\":640},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.masharif.com\/fr\/2018\/09\/17\/lamour-a-deserte-bleue-maissa-boutiche-alger-algerie\/\",\"url\":\"https:\/\/www.masharif.com\/fr\/2018\/09\/17\/lamour-a-deserte-bleue-maissa-boutiche-alger-algerie\/\",\"name\":\"L\u2019amour a d\u00e9sert\u00e9 la bleue par :Maissa Boutiche \u2013 Alger - Alg\u00e9rie - Culminances\",\"isPartOf\":{\"@id\":\"https:\/\/www.masharif.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.masharif.com\/fr\/2018\/09\/17\/lamour-a-deserte-bleue-maissa-boutiche-alger-algerie\/#primaryimage\"},\"datePublished\":\"2018-09-17T13:42:33+00:00\",\"dateModified\":\"2018-09-17T13:42:33+00:00\",\"author\":{\"@id\":\"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/839a7026efe9fa825134097c1041e4a0\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.masharif.com\/fr\/2018\/09\/17\/lamour-a-deserte-bleue-maissa-boutiche-alger-algerie\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.masharif.com\/fr\/2018\/09\/17\/lamour-a-deserte-bleue-maissa-boutiche-alger-algerie\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.masharif.com\/fr\/2018\/09\/17\/lamour-a-deserte-bleue-maissa-boutiche-alger-algerie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.masharif.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u2019amour a d\u00e9sert\u00e9 la bleue par :Maissa Boutiche \u2013 Alger &#8211; Alg\u00e9rie\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/839a7026efe9fa825134097c1041e4a0\",\"name\":\"Mohamed Salah Ben Amor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f64806401ad5ed604ffec2272b19ef46?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f64806401ad5ed604ffec2272b19ef46?s=96&d=identicon&r=g\",\"caption\":\"Mohamed Salah Ben Amor\"},\"sameAs\":[\"http:\/\/ben-amor.info\"],\"url\":\"https:\/\/www.masharif.com\/fr\/author\/msba\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u2019amour a d\u00e9sert\u00e9 la bleue par :Maissa Boutiche \u2013 Alger - Alg\u00e9rie - Culminances","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.masharif.com\/fr\/2018\/09\/17\/lamour-a-deserte-bleue-maissa-boutiche-alger-algerie\/","og_locale":"fr_FR","og_type":"article","og_title":"L\u2019amour a d\u00e9sert\u00e9 la bleue par :Maissa Boutiche \u2013 Alger - Alg\u00e9rie - Culminances","og_description":"&nbsp; Tes vagues dansantes, hier, nous \u00e9gayaient Dans tes bras chauds, tu bordais nos r\u00eaves Entre tes vagues, les sentiments se dandinaient Le c\u0153ur palpitant, \u00a0monte la vague. Les r\u00eaves enfantaient et l\u2019espoir \u00e9tait l\u00e0 L\u2019amour enivrait \u00a0bon nombre de t\u00eates Blessures \u00a0oubli\u00e9es Bleus estompaient Tous leurs maux noyaient dans le chant de tes vagues. ...","og_url":"https:\/\/www.masharif.com\/fr\/2018\/09\/17\/lamour-a-deserte-bleue-maissa-boutiche-alger-algerie\/","og_site_name":"Culminances","article_published_time":"2018-09-17T13:42:33+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/09\/landscape-seaside-3406264_960_720.jpg","type":"image\/jpeg"}],"author":"Mohamed Salah Ben Amor","twitter_card":"summary","twitter_misc":{"\u00c9crit par":"Mohamed Salah Ben Amor","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.masharif.com\/fr\/#website","url":"https:\/\/www.masharif.com\/fr\/","name":"Culminances","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.masharif.com\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.masharif.com\/fr\/2018\/09\/17\/lamour-a-deserte-bleue-maissa-boutiche-alger-algerie\/#primaryimage","url":"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/09\/landscape-seaside-3406264_960_720.jpg","contentUrl":"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/09\/landscape-seaside-3406264_960_720.jpg","width":960,"height":640},{"@type":"WebPage","@id":"https:\/\/www.masharif.com\/fr\/2018\/09\/17\/lamour-a-deserte-bleue-maissa-boutiche-alger-algerie\/","url":"https:\/\/www.masharif.com\/fr\/2018\/09\/17\/lamour-a-deserte-bleue-maissa-boutiche-alger-algerie\/","name":"L\u2019amour a d\u00e9sert\u00e9 la bleue par :Maissa Boutiche \u2013 Alger - Alg\u00e9rie - Culminances","isPartOf":{"@id":"https:\/\/www.masharif.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.masharif.com\/fr\/2018\/09\/17\/lamour-a-deserte-bleue-maissa-boutiche-alger-algerie\/#primaryimage"},"datePublished":"2018-09-17T13:42:33+00:00","dateModified":"2018-09-17T13:42:33+00:00","author":{"@id":"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/839a7026efe9fa825134097c1041e4a0"},"breadcrumb":{"@id":"https:\/\/www.masharif.com\/fr\/2018\/09\/17\/lamour-a-deserte-bleue-maissa-boutiche-alger-algerie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.masharif.com\/fr\/2018\/09\/17\/lamour-a-deserte-bleue-maissa-boutiche-alger-algerie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.masharif.com\/fr\/2018\/09\/17\/lamour-a-deserte-bleue-maissa-boutiche-alger-algerie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.masharif.com\/fr\/"},{"@type":"ListItem","position":2,"name":"L\u2019amour a d\u00e9sert\u00e9 la bleue par :Maissa Boutiche \u2013 Alger &#8211; Alg\u00e9rie"}]},{"@type":"Person","@id":"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/839a7026efe9fa825134097c1041e4a0","name":"Mohamed Salah Ben Amor","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f64806401ad5ed604ffec2272b19ef46?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f64806401ad5ed604ffec2272b19ef46?s=96&d=identicon&r=g","caption":"Mohamed Salah Ben Amor"},"sameAs":["http:\/\/ben-amor.info"],"url":"https:\/\/www.masharif.com\/fr\/author\/msba\/"}]}},"_links":{"self":[{"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/posts\/8809"}],"collection":[{"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/comments?post=8809"}],"version-history":[{"count":1,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/posts\/8809\/revisions"}],"predecessor-version":[{"id":8811,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/posts\/8809\/revisions\/8811"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/media\/8810"}],"wp:attachment":[{"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/media?parent=8809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/categories?post=8809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/tags?post=8809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}