{"id":8123,"date":"2018-05-05T16:16:45","date_gmt":"2018-05-05T15:16:45","guid":{"rendered":"http:\/\/www.masharif.com\/fr\/?p=8123"},"modified":"2018-05-05T16:16:45","modified_gmt":"2018-05-05T15:16:45","slug":"archives-commentaires-poetiques-de-mohamed-salah-ben-amor-11-poemes-de-monique-marie-ihry-11-1-chant-cygne","status":"publish","type":"post","link":"https:\/\/www.masharif.com\/fr\/2018\/05\/05\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-11-poemes-de-monique-marie-ihry-11-1-chant-cygne\/","title":{"rendered":"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor :11 &#8211; Les po\u00e8mes de Monique-Marie Ihry :11 -1 :  Au chant du cygne"},"content":{"rendered":"<div id=\"attachment_8124\" style=\"width: 310px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/05\/11990496_10206370804767881_6880856034801418771_n.jpg\"><img aria-describedby=\"caption-attachment-8124\" loading=\"lazy\" class=\"wp-image-8124 size-medium\" src=\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/05\/11990496_10206370804767881_6880856034801418771_n-300x288.jpg\" alt=\"\" width=\"300\" height=\"288\" srcset=\"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/05\/11990496_10206370804767881_6880856034801418771_n-300x288.jpg 300w, https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/05\/11990496_10206370804767881_6880856034801418771_n.jpg 602w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-8124\" class=\"wp-caption-text\">Monique-Marie Ihry<\/p><\/div>\n<p><a href=\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/05\/13102666_10206572700859482_9220294267961727304_n.jpg\"><img loading=\"lazy\" class=\"alignnone size-medium wp-image-8125\" src=\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/05\/13102666_10206572700859482_9220294267961727304_n-197x300.jpg\" alt=\"\" width=\"197\" height=\"300\" srcset=\"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/05\/13102666_10206572700859482_9220294267961727304_n-197x300.jpg 197w, https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/05\/13102666_10206572700859482_9220294267961727304_n.jpg 263w\" sizes=\"(max-width: 197px) 100vw, 197px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>I<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>La mort, tel un oiseau de proie<\/strong><\/p>\n<p><strong>D\u00e9ploya ses ailes immenses.<\/strong><\/p>\n<p><strong>Ses serres avec v\u00e9h\u00e9mence<\/strong><\/p>\n<p><strong>Griff\u00e8rent l\u2019harmonie de soie<\/strong><\/p>\n<p><strong>Recouvrant les vagues azur<\/strong><\/p>\n<p><strong>D\u2019ombres argent\u00e9es, lumineuses.<\/strong><\/p>\n<p><strong>De ses longues ailes fl\u00e2neuses<\/strong><\/p>\n<p><strong>L\u2019oiseau de mort au regard dur<\/strong><\/p>\n<p><strong>Fendit le bleu miroir de l\u2019onde,<\/strong><\/p>\n<p><strong>Puis rebondit d\u2019un coup de rein<\/strong><\/p>\n<p><strong>Vers les hauts cieux faits d\u2019airain<\/strong><\/p>\n<p><strong>Laissant mon \u00e2me vagabonde<\/strong><\/p>\n<p><strong>Voguer, pour un temps seulement,<\/strong><\/p>\n<p><strong>Un temps de r\u00e9pit sur la vie,<\/strong><\/p>\n<p><strong>Rien qu\u2019un court instant de survie<\/strong><\/p>\n<p><strong>Avant la nuit, fatalement\u2026<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 II<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>L\u2019oiseau de mort revint fr\u00f4lant<\/strong><\/p>\n<p><strong>Ma barque frileuse amarr\u00e9e.<\/strong><\/p>\n<p><strong>Je le regardai, effar\u00e9e,<\/strong><\/p>\n<p><strong>Verser son filet nonchalant<\/strong><\/p>\n<p><strong>Sur mes esp\u00e9rances ultimes.<\/strong><\/p>\n<p><strong>La mer eut des relents de sang,<\/strong><\/p>\n<p><strong>Puis l\u2019onde se grisa d\u2019encens<\/strong><\/p>\n<p><strong>En m\u2019attirant dans ses ab\u00eemes\u2026<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 III<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Dans l\u2019antre de la mer, enfin<\/strong><\/p>\n<p><strong>Je crus entrevoir la lumi\u00e8re\u00a0;<\/strong><\/p>\n<p><strong>Elle me parut famili\u00e8re.<\/strong><\/p>\n<p><strong>J\u2019\u00e9tais \u00e0 deux doigts de la fin<\/strong><\/p>\n<p><strong>C\u2019\u00e9tait si doux dans l\u2019onde claire.<\/strong><\/p>\n<p><strong>Un tapis d\u2019algues m\u2019accueillait, <\/strong><\/p>\n<p><strong>La mort sereine me cueillait<\/strong><\/p>\n<p><strong>Telle la fleur ab\u00e9c\u00e9daire<\/strong><\/p>\n<p><strong>D\u2019un dictionnaire des d\u00e9c\u00e8s.<\/strong><\/p>\n<p><strong>J\u2019eus soudain tr\u00e8s envie de vivre,<\/strong><\/p>\n<p><strong>Me lib\u00e9rai d\u2019un \u00e9lan ivre<\/strong><\/p>\n<p><strong>D\u2019entre les mailles du corset.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 IV<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Une fois parvenue au jour,<\/strong><\/p>\n<p><strong>Lib\u00e9r\u00e9e du carcan liquide<\/strong><\/p>\n<p><strong>Orchestr\u00e9 par la mort, son vide,<\/strong><\/p>\n<p><strong>J\u2019osai esp\u00e9rer un amour<\/strong><\/p>\n<p><strong>Qui viendrait orchestrer mon c\u0153ur.<\/strong><\/p>\n<p><strong>Je priai pour que cette vie<\/strong><\/p>\n<p><strong>Vogue au-del\u00e0 de la survie<\/strong><\/p>\n<p><strong>Et verse enfin dans le bonheur\u00a0!<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>V<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Dans le ciel scintillait la Lune<\/strong><\/p>\n<p><strong>Entour\u00e9e d\u2019astres lumineux,<\/strong><\/p>\n<p><strong>Tous les nuages charbonneux<\/strong><\/p>\n<p><strong>Avaient d\u00e9sert\u00e9 la nuit brune.<\/strong><\/p>\n<p><strong>La mort rangeait ses longs filets<\/strong><\/p>\n<p><strong>Sur le sable gris\u00e9 de cendre.<\/strong><\/p>\n<p><strong>Une brise l\u00e9g\u00e8re et tendre<\/strong><\/p>\n<p><strong>Chantonnait au soir ses couplets,<\/strong><\/p>\n<p><strong>Refrain chaleureux sur la toile<\/strong><\/p>\n<p><strong>De l\u2019univers. Je m\u2019endormis<\/strong><\/p>\n<p><strong>D\u2019un sommeil aux r\u00eaves ravis,<\/strong><\/p>\n<p><strong>Loin de la mort et de son voile\u2026<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 VI<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Je m\u2019\u00e9veillai sur une plage<\/strong><\/p>\n<p><strong>Baign\u00e9e d\u2019un soleil chaleureux. <\/strong><\/p>\n<p><strong>Les grands pins voguaient bienheureux<\/strong><\/p>\n<p><strong>Entre les vagues d\u2019un nuage.<\/strong><\/p>\n<p><strong>Le ciel soudain se fit azur,<\/strong><\/p>\n<p><strong>Un cygne \u00e9crivit un long vers,<\/strong><\/p>\n<p><strong>Un signe inscrit sur l\u2019univers<\/strong><\/p>\n<p><strong>Pour louer la vie, un futur\u2026<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 VII<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Le cygne fendait l\u2019eau, majestueux et beau,<\/strong><\/p>\n<p><strong>Dans le cr\u00e9puscule s\u2019\u00e9veillaient les \u00e9toiles<\/strong><\/p>\n<p><strong>Dissipant peu \u00e0 peu les brumes de leur voile,<\/strong><\/p>\n<p><strong>L\u2019ange dans les cieux semblait b\u00e9nir les flots.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Au loin l\u2019on entendait des chevaux les sabots.<\/strong><\/p>\n<p><strong>Le bruit de leur course dans le soir automnal<\/strong><\/p>\n<p><strong>Finit par agonir de ses pas en rafale<\/strong><\/p>\n<p><strong>Dans le silence bleu d\u2019une nuit sans tombeaux.<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Le cygne blanc nageait au rythme de la lune<\/strong><\/p>\n<p><strong>Dont le chant bienveillant aux notes opportunes<\/strong><\/p>\n<p><strong>Charmait l\u2019onde sereine et comblait d\u2019infini<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Le monde s\u2019endormait dans la blonde harmonie<\/strong><\/p>\n<p><strong>D\u2019une paix recouvr\u00e9e, remettait \u00e0 demain<\/strong><\/p>\n<p><strong>L\u2019enfer de la guerre, ses fers, son venin\u2026<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Extrait du recueil de po\u00e9sie <strong><em>Cueillir les roses de l\u2019oubli<\/em><\/strong>, \u00c9ditions Mille-Po\u00e8tes en M\u00e9diterran\u00e9e, Narbonne, 2014<\/p>\n<p>&nbsp;<\/p>\n<p>* * *<\/p>\n<p>La premi\u00e8re remarque qui se d\u00e9gage de ce po\u00e8me autobiographique \u00e9crit \u00e0 la premi\u00e8re personne, est\u00a0que son auteure, habitu\u00e9e formellement aux po\u00e8mes\u00a0de longueur moyenne, a \u00e9prouv\u00e9 cette fois le besoin d\u2019utiliser le po\u00e8me tr\u00e8s long (78 vers). La cause \u00e0 l\u2019origine de ce changement est qu\u2019elle tente de faire un bilan de son existence\u00a0d\u2019adulte\u00a0; celle-ci se compose, selon ses dires, de deux \u00e9tapes distinctes. La premi\u00e8re \u00e9tait marqu\u00e9e par l\u2019infortune et la cruaut\u00e9 du destin. Dans la seconde qui se poursuit au pr\u00e9sent, elle a trouv\u00e9 la qui\u00e9tude et le bonheur. Cette division nette du parcours de la locutrice l\u2019a aid\u00e9e \u00e0 bien traiter son texte esth\u00e9tiquement et ce, en usant simultan\u00e9ment de deux proc\u00e9d\u00e9s majeurs\u00a0: la technique de la temporalit\u00e9 et la m\u00e9taphorisation. Ainsi, pour mettre en \u00e9vidence l\u2019atrocit\u00e9 de la premi\u00e8re \u00e9tape et bien la s\u00e9parer de la seconde, elle a utilis\u00e9 le symbole de l\u2019oiseau de mort et le <em>flash-back<\/em>, tandis que dans la deuxi\u00e8me \u00e9tape qu\u2019elle pr\u00e9sente comme empreinte de bonheur, elle a choisi le symbole contraire du cygne et le temps pr\u00e9sent.<\/p>\n<p>La seconde remarque \u00e0 faire est que tous les \u00e9v\u00e9nements relat\u00e9s ici \u00a0se passent \u00e0 l\u2019int\u00e9rieur de la locutrice, d\u2019o\u00f9 le caract\u00e8re purement psychologique du po\u00e8me qui offre au lecteur une sorte d\u2019auto-analyse introspective plongeant, d\u2019abord, dans la m\u00e9moire pour r\u00e9veiller des souvenirs obscurs douloureux formant un v\u00e9ritable cauchemar, ensuite dans l\u2019esprit \u00e9veill\u00e9 pour d\u00e9crire les sentiments de bien-\u00eatre et de s\u00e9r\u00e9nit\u00e9 que l\u2019auteure \u00e9prouve au temps de l\u2019\u00e9nonciation.<\/p>\n<p>Un po\u00e8me magistral qui retrace admirablement une bonne partie de l\u2019itin\u00e9raire individuel de la po\u00e9tesse et qui s\u00e9duit par l\u2019originalit\u00e9 de ses images et la charge \u00e9motionnelle de ses mots.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; I \u00a0 La mort, tel un oiseau de proie D\u00e9ploya ses ailes immenses. Ses serres avec v\u00e9h\u00e9mence Griff\u00e8rent l\u2019harmonie de soie Recouvrant les vagues azur D\u2019ombres argent\u00e9es, lumineuses. De ses longues ailes fl\u00e2neuses L\u2019oiseau de mort au regard dur Fendit le bleu miroir de l\u2019onde, Puis rebondit d\u2019un coup de rein Vers les &#8230;<\/p>\n","protected":false},"author":2,"featured_media":8124,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor :11 - Les po\u00e8mes de Monique-Marie Ihry :11 -1 : Au chant du cygne - Culminances<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.masharif.com\/fr\/2018\/05\/05\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-11-poemes-de-monique-marie-ihry-11-1-chant-cygne\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor :11 - Les po\u00e8mes de Monique-Marie Ihry :11 -1 : Au chant du cygne - Culminances\" \/>\n<meta property=\"og:description\" content=\"&nbsp; &nbsp; I \u00a0 La mort, tel un oiseau de proie D\u00e9ploya ses ailes immenses. Ses serres avec v\u00e9h\u00e9mence Griff\u00e8rent l\u2019harmonie de soie Recouvrant les vagues azur D\u2019ombres argent\u00e9es, lumineuses. De ses longues ailes fl\u00e2neuses L\u2019oiseau de mort au regard dur Fendit le bleu miroir de l\u2019onde, Puis rebondit d\u2019un coup de rein Vers les ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.masharif.com\/fr\/2018\/05\/05\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-11-poemes-de-monique-marie-ihry-11-1-chant-cygne\/\" \/>\n<meta property=\"og:site_name\" content=\"Culminances\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-05T15:16:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/05\/11990496_10206370804767881_6880856034801418771_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"602\" \/>\n\t<meta property=\"og:image:height\" content=\"577\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mohamed Salah Ben Amor\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mohamed Salah Ben Amor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.masharif.com\/fr\/#website\",\"url\":\"https:\/\/www.masharif.com\/fr\/\",\"name\":\"Culminances\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.masharif.com\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.masharif.com\/fr\/2018\/05\/05\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-11-poemes-de-monique-marie-ihry-11-1-chant-cygne\/#primaryimage\",\"url\":\"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/05\/11990496_10206370804767881_6880856034801418771_n.jpg\",\"contentUrl\":\"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/05\/11990496_10206370804767881_6880856034801418771_n.jpg\",\"width\":602,\"height\":577},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.masharif.com\/fr\/2018\/05\/05\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-11-poemes-de-monique-marie-ihry-11-1-chant-cygne\/\",\"url\":\"https:\/\/www.masharif.com\/fr\/2018\/05\/05\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-11-poemes-de-monique-marie-ihry-11-1-chant-cygne\/\",\"name\":\"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor :11 - Les po\u00e8mes de Monique-Marie Ihry :11 -1 : Au chant du cygne - Culminances\",\"isPartOf\":{\"@id\":\"https:\/\/www.masharif.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.masharif.com\/fr\/2018\/05\/05\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-11-poemes-de-monique-marie-ihry-11-1-chant-cygne\/#primaryimage\"},\"datePublished\":\"2018-05-05T15:16:45+00:00\",\"dateModified\":\"2018-05-05T15:16:45+00:00\",\"author\":{\"@id\":\"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/839a7026efe9fa825134097c1041e4a0\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.masharif.com\/fr\/2018\/05\/05\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-11-poemes-de-monique-marie-ihry-11-1-chant-cygne\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.masharif.com\/fr\/2018\/05\/05\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-11-poemes-de-monique-marie-ihry-11-1-chant-cygne\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.masharif.com\/fr\/2018\/05\/05\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-11-poemes-de-monique-marie-ihry-11-1-chant-cygne\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.masharif.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor :11 &#8211; Les po\u00e8mes de Monique-Marie Ihry :11 -1 : Au chant du cygne\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/839a7026efe9fa825134097c1041e4a0\",\"name\":\"Mohamed Salah Ben Amor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f64806401ad5ed604ffec2272b19ef46?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f64806401ad5ed604ffec2272b19ef46?s=96&d=identicon&r=g\",\"caption\":\"Mohamed Salah Ben Amor\"},\"sameAs\":[\"http:\/\/ben-amor.info\"],\"url\":\"https:\/\/www.masharif.com\/fr\/author\/msba\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor :11 - Les po\u00e8mes de Monique-Marie Ihry :11 -1 : Au chant du cygne - Culminances","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.masharif.com\/fr\/2018\/05\/05\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-11-poemes-de-monique-marie-ihry-11-1-chant-cygne\/","og_locale":"fr_FR","og_type":"article","og_title":"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor :11 - Les po\u00e8mes de Monique-Marie Ihry :11 -1 : Au chant du cygne - Culminances","og_description":"&nbsp; &nbsp; I \u00a0 La mort, tel un oiseau de proie D\u00e9ploya ses ailes immenses. Ses serres avec v\u00e9h\u00e9mence Griff\u00e8rent l\u2019harmonie de soie Recouvrant les vagues azur D\u2019ombres argent\u00e9es, lumineuses. De ses longues ailes fl\u00e2neuses L\u2019oiseau de mort au regard dur Fendit le bleu miroir de l\u2019onde, Puis rebondit d\u2019un coup de rein Vers les ...","og_url":"https:\/\/www.masharif.com\/fr\/2018\/05\/05\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-11-poemes-de-monique-marie-ihry-11-1-chant-cygne\/","og_site_name":"Culminances","article_published_time":"2018-05-05T15:16:45+00:00","og_image":[{"width":602,"height":577,"url":"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/05\/11990496_10206370804767881_6880856034801418771_n.jpg","type":"image\/jpeg"}],"author":"Mohamed Salah Ben Amor","twitter_card":"summary","twitter_misc":{"\u00c9crit par":"Mohamed Salah Ben Amor","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.masharif.com\/fr\/#website","url":"https:\/\/www.masharif.com\/fr\/","name":"Culminances","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.masharif.com\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.masharif.com\/fr\/2018\/05\/05\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-11-poemes-de-monique-marie-ihry-11-1-chant-cygne\/#primaryimage","url":"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/05\/11990496_10206370804767881_6880856034801418771_n.jpg","contentUrl":"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/05\/11990496_10206370804767881_6880856034801418771_n.jpg","width":602,"height":577},{"@type":"WebPage","@id":"https:\/\/www.masharif.com\/fr\/2018\/05\/05\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-11-poemes-de-monique-marie-ihry-11-1-chant-cygne\/","url":"https:\/\/www.masharif.com\/fr\/2018\/05\/05\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-11-poemes-de-monique-marie-ihry-11-1-chant-cygne\/","name":"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor :11 - Les po\u00e8mes de Monique-Marie Ihry :11 -1 : Au chant du cygne - Culminances","isPartOf":{"@id":"https:\/\/www.masharif.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.masharif.com\/fr\/2018\/05\/05\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-11-poemes-de-monique-marie-ihry-11-1-chant-cygne\/#primaryimage"},"datePublished":"2018-05-05T15:16:45+00:00","dateModified":"2018-05-05T15:16:45+00:00","author":{"@id":"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/839a7026efe9fa825134097c1041e4a0"},"breadcrumb":{"@id":"https:\/\/www.masharif.com\/fr\/2018\/05\/05\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-11-poemes-de-monique-marie-ihry-11-1-chant-cygne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.masharif.com\/fr\/2018\/05\/05\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-11-poemes-de-monique-marie-ihry-11-1-chant-cygne\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.masharif.com\/fr\/2018\/05\/05\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-11-poemes-de-monique-marie-ihry-11-1-chant-cygne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.masharif.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor :11 &#8211; Les po\u00e8mes de Monique-Marie Ihry :11 -1 : Au chant du cygne"}]},{"@type":"Person","@id":"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/839a7026efe9fa825134097c1041e4a0","name":"Mohamed Salah Ben Amor","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f64806401ad5ed604ffec2272b19ef46?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f64806401ad5ed604ffec2272b19ef46?s=96&d=identicon&r=g","caption":"Mohamed Salah Ben Amor"},"sameAs":["http:\/\/ben-amor.info"],"url":"https:\/\/www.masharif.com\/fr\/author\/msba\/"}]}},"_links":{"self":[{"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/posts\/8123"}],"collection":[{"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/comments?post=8123"}],"version-history":[{"count":1,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/posts\/8123\/revisions"}],"predecessor-version":[{"id":8126,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/posts\/8123\/revisions\/8126"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/media\/8124"}],"wp:attachment":[{"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/media?parent=8123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/categories?post=8123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/tags?post=8123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}