{"id":8008,"date":"2018-04-24T20:04:25","date_gmt":"2018-04-24T19:04:25","guid":{"rendered":"http:\/\/www.masharif.com\/fr\/?p=8008"},"modified":"2018-04-24T20:04:25","modified_gmt":"2018-04-24T19:04:25","slug":"archives-commentaires-poetiques-de-mohamed-salah-ben-amor-6les-poemes-de-solene-de-lam-6-8-demain","status":"publish","type":"post","link":"https:\/\/www.masharif.com\/fr\/2018\/04\/24\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-6les-poemes-de-solene-de-lam-6-8-demain\/","title":{"rendered":"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor :6:Les po\u00e8mes de Sol\u00e8ne de Lam :6 -8 : Demain"},"content":{"rendered":"<div id=\"attachment_7528\" style=\"width: 310px\" class=\"wp-caption alignnone\"><a href=\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/03\/10559899_10202415362527803_4517410004001902300_n.jpg\"><img aria-describedby=\"caption-attachment-7528\" loading=\"lazy\" class=\"wp-image-7528 size-medium\" src=\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/03\/10559899_10202415362527803_4517410004001902300_n-300x294.jpg\" alt=\"\" width=\"300\" height=\"294\" srcset=\"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/03\/10559899_10202415362527803_4517410004001902300_n-300x294.jpg 300w, https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/03\/10559899_10202415362527803_4517410004001902300_n-768x752.jpg 768w, https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/03\/10559899_10202415362527803_4517410004001902300_n-55x55.jpg 55w, https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/03\/10559899_10202415362527803_4517410004001902300_n.jpg 994w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><p id=\"caption-attachment-7528\" class=\"wp-caption-text\">Sol\u00e8ne de Lam<\/p><\/div>\n<p><a href=\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/04\/car-1967698_960_720.jpg\"><img loading=\"lazy\" class=\"alignnone size-medium wp-image-8009\" src=\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/04\/car-1967698_960_720-181x300.jpg\" alt=\"\" width=\"181\" height=\"300\" srcset=\"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/04\/car-1967698_960_720-181x300.jpg 181w, https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/04\/car-1967698_960_720.jpg 434w\" sizes=\"(max-width: 181px) 100vw, 181px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Demain, je ne serai peut-\u00eatre plus moi-m\u00eame<\/strong><\/p>\n<p><strong>Le temps pass\u00e9, sera pass\u00e9,<\/strong><\/p>\n<p><strong>j&#8217;aurai peut-\u00eatre tr\u00e9pass\u00e9<\/strong><\/p>\n<p><strong>A l&#8217;aube, le c\u0153ur serr\u00e9,<\/strong><\/p>\n<p><strong>j&#8217;irai demander les augures<\/strong><\/p>\n<p><strong>Dois-je finir esclave de ma nature ?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Demain le jour sera lev\u00e9, j&#8217;aurai souris<\/strong><\/p>\n<p><strong>Je me dirai peut-\u00eatre, c&#8217;\u00e9tait si beau la vie !<\/strong><\/p>\n<p><strong>Ne sachant pas o\u00f9 la vie nous emm\u00e8ne<\/strong><\/p>\n<p><strong>Je me lierai peut-\u00eatre \u00e0 mes cha\u00eenes ?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Demain sera peut-\u00eatre le lendemain<\/strong><\/p>\n<p><strong>De ce jour-l\u00e0. Je ne sais si ce sera bien&#8230;<\/strong><\/p>\n<p><strong>Mise \u00e0 l&#8217;\u00e9cart de moi-m\u00eame, et folle<\/strong><\/p>\n<p><strong>J&#8217;irais peut-\u00eatre danser seule ma farandole<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Se faisant d\u2019habitude chantre d\u2019un amour r\u00e9ciproque merveilleusement partag\u00e9 suscitant\u00a0 le summum du bonheur et la cime de la jouissance ,c\u2019est la premi\u00e8re fois que l\u2019auteure de ce po\u00e8me s\u2019\u00e9carte de ce th\u00e8me,\u00a0 non seulement pour en aborder un autre mais cet autre lui est totalement oppos\u00e9 de par les pr\u00e9occupations chagrinantes qui lui sont li\u00e9es .Et m\u00eame si l\u2019on suppose que \u00a0ce revirement soit accidentel ou momentan\u00e9 , il ne manque pas de susciter des interrogations sur ses causes .Le penseur Andalou\u00a0 Ibn Hazm( \u00a0384 -994 apr\u00e8s J-C. ) , l\u2019auteur du fameux trait\u00e9 sur l\u2019amour intitul\u00e9\u00a0<em>Le collier du pigeon<\/em>\u00a0\u00a0nous r\u00e9pond que m\u00eame \u00e0 l\u2019apoth\u00e9ose du bonheur, l\u2019amoureux n\u2019a jamais l\u2019esprit tranquille, car il a peur de perdre ce dont il jouit \u00e0 l\u2019instant pr\u00e9sent et de ce que lui cache le lendemain .Et cette phobie du futur est exprim\u00e9e dans ce po\u00e8me sous forme\u00a0 d\u2019une inqui\u00e9tude irraisonn\u00e9e et obs\u00e9dante renforc\u00e9e par un sentiment d\u2019impuissance \u00e0 changer le cours du temps (<strong>ne sachant pas o\u00f9 la vie nous emm\u00e8ne &#8211; demain sera peut-\u00eatre le lendemain de ce jour-l\u00e0 <\/strong>)\u00a0\u00a0 et l\u2019adoption d\u2019une position de passivit\u00e9 vis-\u00e0-vis de ce futur \u00a0(<strong>je ne serai peut-\u00eatre plus moi-m\u00eame &#8211; dois-je finir esclave de ma nature\u00a0? &#8211; je me lierai peut-\u00eatre \u00e0 mes cha\u00eenes ? &#8211; mise \u00e0 l&#8217;\u00e9cart de moi-m\u00eame<\/strong>).Ce qui nous met en face d\u2019une v\u00e9ritable crise existentielle .Et la preuve en est que cet \u00e9tat plus psychique (c.\u00e0.d. mental) que psychologique (c.\u00e0.d. affectif et \u00e9motionnel) aboutit \u00e0 un \u00a0marasme marqu\u00e9 par un d\u00e9raisonnement total\u00a0 (<strong>folle j&#8217;irais peut-\u00eatre danser seule ma farandole<\/strong>).Ce qui montre l\u2019extr\u00eame pr\u00e9carit\u00e9 du sentiment amoureux qui peut \u00e0 n\u2019importe quel moment et sans causes objectives basculer dans le pire.<\/p>\n<p>Sur le plan stylistique, deux traits attirent particuli\u00e8rement l\u2019attention\u00a0: l\u2019usage massif de vocables exprimant le doute (l\u2019adverbe &#8220;peut-\u00eatre&#8221; repris 5 fois en 13 vers \u00a0\u00a0plus deux phrases interrogatives) impliqu\u00e9 par la nature du th\u00e8me abord\u00e9 et l\u2019image surprenante finale de la danse folle.<\/p>\n<p>Un bon po\u00e8me! Mes encouragements Sol\u00e8ne !<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Demain, je ne serai peut-\u00eatre plus moi-m\u00eame Le temps pass\u00e9, sera pass\u00e9, j&#8217;aurai peut-\u00eatre tr\u00e9pass\u00e9 A l&#8217;aube, le c\u0153ur serr\u00e9, j&#8217;irai demander les augures Dois-je finir esclave de ma nature ? &nbsp; Demain le jour sera lev\u00e9, j&#8217;aurai souris Je me dirai peut-\u00eatre, c&#8217;\u00e9tait si beau la vie ! Ne sachant pas o\u00f9 &#8230;<\/p>\n","protected":false},"author":2,"featured_media":7528,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor :6:Les po\u00e8mes de Sol\u00e8ne de Lam :6 -8 : Demain - Culminances<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.masharif.com\/fr\/2018\/04\/24\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-6les-poemes-de-solene-de-lam-6-8-demain\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor :6:Les po\u00e8mes de Sol\u00e8ne de Lam :6 -8 : Demain - Culminances\" \/>\n<meta property=\"og:description\" content=\"&nbsp; &nbsp; Demain, je ne serai peut-\u00eatre plus moi-m\u00eame Le temps pass\u00e9, sera pass\u00e9, j&#8217;aurai peut-\u00eatre tr\u00e9pass\u00e9 A l&#8217;aube, le c\u0153ur serr\u00e9, j&#8217;irai demander les augures Dois-je finir esclave de ma nature ? &nbsp; Demain le jour sera lev\u00e9, j&#8217;aurai souris Je me dirai peut-\u00eatre, c&#8217;\u00e9tait si beau la vie ! Ne sachant pas o\u00f9 ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.masharif.com\/fr\/2018\/04\/24\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-6les-poemes-de-solene-de-lam-6-8-demain\/\" \/>\n<meta property=\"og:site_name\" content=\"Culminances\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-24T19:04:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/03\/10559899_10202415362527803_4517410004001902300_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"994\" \/>\n\t<meta property=\"og:image:height\" content=\"973\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mohamed Salah Ben Amor\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mohamed Salah Ben Amor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.masharif.com\/fr\/#website\",\"url\":\"https:\/\/www.masharif.com\/fr\/\",\"name\":\"Culminances\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.masharif.com\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.masharif.com\/fr\/2018\/04\/24\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-6les-poemes-de-solene-de-lam-6-8-demain\/#primaryimage\",\"url\":\"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/03\/10559899_10202415362527803_4517410004001902300_n.jpg\",\"contentUrl\":\"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/03\/10559899_10202415362527803_4517410004001902300_n.jpg\",\"width\":994,\"height\":973},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.masharif.com\/fr\/2018\/04\/24\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-6les-poemes-de-solene-de-lam-6-8-demain\/\",\"url\":\"https:\/\/www.masharif.com\/fr\/2018\/04\/24\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-6les-poemes-de-solene-de-lam-6-8-demain\/\",\"name\":\"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor :6:Les po\u00e8mes de Sol\u00e8ne de Lam :6 -8 : Demain - Culminances\",\"isPartOf\":{\"@id\":\"https:\/\/www.masharif.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.masharif.com\/fr\/2018\/04\/24\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-6les-poemes-de-solene-de-lam-6-8-demain\/#primaryimage\"},\"datePublished\":\"2018-04-24T19:04:25+00:00\",\"dateModified\":\"2018-04-24T19:04:25+00:00\",\"author\":{\"@id\":\"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/839a7026efe9fa825134097c1041e4a0\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.masharif.com\/fr\/2018\/04\/24\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-6les-poemes-de-solene-de-lam-6-8-demain\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.masharif.com\/fr\/2018\/04\/24\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-6les-poemes-de-solene-de-lam-6-8-demain\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.masharif.com\/fr\/2018\/04\/24\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-6les-poemes-de-solene-de-lam-6-8-demain\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.masharif.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor :6:Les po\u00e8mes de Sol\u00e8ne de Lam :6 -8 : Demain\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/839a7026efe9fa825134097c1041e4a0\",\"name\":\"Mohamed Salah Ben Amor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/f64806401ad5ed604ffec2272b19ef46?s=96&d=identicon&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/f64806401ad5ed604ffec2272b19ef46?s=96&d=identicon&r=g\",\"caption\":\"Mohamed Salah Ben Amor\"},\"sameAs\":[\"http:\/\/ben-amor.info\"],\"url\":\"https:\/\/www.masharif.com\/fr\/author\/msba\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor :6:Les po\u00e8mes de Sol\u00e8ne de Lam :6 -8 : Demain - Culminances","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.masharif.com\/fr\/2018\/04\/24\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-6les-poemes-de-solene-de-lam-6-8-demain\/","og_locale":"fr_FR","og_type":"article","og_title":"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor :6:Les po\u00e8mes de Sol\u00e8ne de Lam :6 -8 : Demain - Culminances","og_description":"&nbsp; &nbsp; Demain, je ne serai peut-\u00eatre plus moi-m\u00eame Le temps pass\u00e9, sera pass\u00e9, j&#8217;aurai peut-\u00eatre tr\u00e9pass\u00e9 A l&#8217;aube, le c\u0153ur serr\u00e9, j&#8217;irai demander les augures Dois-je finir esclave de ma nature ? &nbsp; Demain le jour sera lev\u00e9, j&#8217;aurai souris Je me dirai peut-\u00eatre, c&#8217;\u00e9tait si beau la vie ! Ne sachant pas o\u00f9 ...","og_url":"https:\/\/www.masharif.com\/fr\/2018\/04\/24\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-6les-poemes-de-solene-de-lam-6-8-demain\/","og_site_name":"Culminances","article_published_time":"2018-04-24T19:04:25+00:00","og_image":[{"width":994,"height":973,"url":"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/03\/10559899_10202415362527803_4517410004001902300_n.jpg","type":"image\/jpeg"}],"author":"Mohamed Salah Ben Amor","twitter_card":"summary","twitter_misc":{"\u00c9crit par":"Mohamed Salah Ben Amor","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.masharif.com\/fr\/#website","url":"https:\/\/www.masharif.com\/fr\/","name":"Culminances","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.masharif.com\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.masharif.com\/fr\/2018\/04\/24\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-6les-poemes-de-solene-de-lam-6-8-demain\/#primaryimage","url":"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/03\/10559899_10202415362527803_4517410004001902300_n.jpg","contentUrl":"https:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2018\/03\/10559899_10202415362527803_4517410004001902300_n.jpg","width":994,"height":973},{"@type":"WebPage","@id":"https:\/\/www.masharif.com\/fr\/2018\/04\/24\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-6les-poemes-de-solene-de-lam-6-8-demain\/","url":"https:\/\/www.masharif.com\/fr\/2018\/04\/24\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-6les-poemes-de-solene-de-lam-6-8-demain\/","name":"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor :6:Les po\u00e8mes de Sol\u00e8ne de Lam :6 -8 : Demain - Culminances","isPartOf":{"@id":"https:\/\/www.masharif.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.masharif.com\/fr\/2018\/04\/24\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-6les-poemes-de-solene-de-lam-6-8-demain\/#primaryimage"},"datePublished":"2018-04-24T19:04:25+00:00","dateModified":"2018-04-24T19:04:25+00:00","author":{"@id":"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/839a7026efe9fa825134097c1041e4a0"},"breadcrumb":{"@id":"https:\/\/www.masharif.com\/fr\/2018\/04\/24\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-6les-poemes-de-solene-de-lam-6-8-demain\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.masharif.com\/fr\/2018\/04\/24\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-6les-poemes-de-solene-de-lam-6-8-demain\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.masharif.com\/fr\/2018\/04\/24\/archives-commentaires-poetiques-de-mohamed-salah-ben-amor-6les-poemes-de-solene-de-lam-6-8-demain\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.masharif.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Les archives des commentaires po\u00e9tiques de Mohamed Salah Ben Amor :6:Les po\u00e8mes de Sol\u00e8ne de Lam :6 -8 : Demain"}]},{"@type":"Person","@id":"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/839a7026efe9fa825134097c1041e4a0","name":"Mohamed Salah Ben Amor","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.masharif.com\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/f64806401ad5ed604ffec2272b19ef46?s=96&d=identicon&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f64806401ad5ed604ffec2272b19ef46?s=96&d=identicon&r=g","caption":"Mohamed Salah Ben Amor"},"sameAs":["http:\/\/ben-amor.info"],"url":"https:\/\/www.masharif.com\/fr\/author\/msba\/"}]}},"_links":{"self":[{"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/posts\/8008"}],"collection":[{"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/comments?post=8008"}],"version-history":[{"count":1,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/posts\/8008\/revisions"}],"predecessor-version":[{"id":8010,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/posts\/8008\/revisions\/8010"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/media\/7528"}],"wp:attachment":[{"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/media?parent=8008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/categories?post=8008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/tags?post=8008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}