{"id":11328,"date":"2021-05-07T18:11:29","date_gmt":"2021-05-07T17:11:29","guid":{"rendered":"http:\/\/www.masharif.com\/fr\/?p=11328"},"modified":"2021-05-07T18:11:30","modified_gmt":"2021-05-07T17:11:30","slug":"ou-sont-vos-airs-narquois-meprisables-par-ahmed-safir-fes-maroc","status":"publish","type":"post","link":"http:\/\/www.masharif.com\/fr\/2021\/05\/07\/ou-sont-vos-airs-narquois-meprisables-par-ahmed-safir-fes-maroc\/","title":{"rendered":"O\u00f9 sont vos airs narquois, m\u00e9prisables? par: Ahmed Safir- F\u00e8s -Maroc"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"780\" height=\"791\" src=\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2021\/01\/t\u00e9l\u00e9chargement-1.jpg\" alt=\"\" class=\"wp-image-11097\" srcset=\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2021\/01\/t\u00e9l\u00e9chargement-1.jpg 780w, http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2021\/01\/t\u00e9l\u00e9chargement-1-296x300.jpg 296w, http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2021\/01\/t\u00e9l\u00e9chargement-1-768x779.jpg 768w, http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2021\/01\/t\u00e9l\u00e9chargement-1-55x55.jpg 55w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" width=\"450\" height=\"450\" src=\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2021\/05\/kristiano160700037.jpg\" alt=\"\" class=\"wp-image-11329\" srcset=\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2021\/05\/kristiano160700037.jpg 450w, http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2021\/05\/kristiano160700037-150x150.jpg 150w, http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2021\/05\/kristiano160700037-300x300.jpg 300w, http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2021\/05\/kristiano160700037-55x55.jpg 55w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/figure>\n\n\n\n<p><strong>O\u00f9 sont vos airs narquois, m\u00e9prisables <br> A quoi sert v\u00f4tre fortune in\u00e9puisable <br> Vous qui avez longtemps m\u00e9pris\u00e9 vos semblables <br> O\u00f9 sont vos airs de grandeur<br> Vos faux airs de grands seigneurs<br> Vos parfums import\u00e9s d&#8217;ailleurs<br> Vos voitures de luxe, vos tailleurs<br> Vous qui pr\u00e9tendiez \u00eatre les meilleurs <br> Aujourd&#8217;hui vous tremblez de peur<br> Devant cette chose dont vous avez horreur <br> Ce minus, ce virus, si petit mais grand tueur<br> V\u00f4tre fortune et vos armes <br> Ne peuvent s\u00e9cher vos larmes <br> Vous avez perdu le calme<br> Le moindre souffle vous alarme.<br> <br> <\/strong>Ahmed Safir<strong><br> <br> <\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O\u00f9 sont vos airs narquois, m\u00e9prisables A quoi sert v\u00f4tre fortune in\u00e9puisable Vous qui avez longtemps m\u00e9pris\u00e9 vos semblables O\u00f9 sont vos airs de grandeur Vos faux airs de grands seigneurs Vos parfums import\u00e9s d&#8217;ailleurs Vos voitures de luxe, vos tailleurs Vous qui pr\u00e9tendiez \u00eatre les meilleurs Aujourd&#8217;hui vous tremblez de peur Devant cette chose &#8230;<\/p>\n","protected":false},"author":2,"featured_media":11329,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>O\u00f9 sont vos airs narquois, m\u00e9prisables? par: Ahmed Safir- F\u00e8s -Maroc - Culminances<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.masharif.com\/fr\/2021\/05\/07\/ou-sont-vos-airs-narquois-meprisables-par-ahmed-safir-fes-maroc\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O\u00f9 sont vos airs narquois, m\u00e9prisables? par: Ahmed Safir- F\u00e8s -Maroc - Culminances\" \/>\n<meta property=\"og:description\" content=\"O\u00f9 sont vos airs narquois, m\u00e9prisables A quoi sert v\u00f4tre fortune in\u00e9puisable Vous qui avez longtemps m\u00e9pris\u00e9 vos semblables O\u00f9 sont vos airs de grandeur Vos faux airs de grands seigneurs Vos parfums import\u00e9s d&#8217;ailleurs Vos voitures de luxe, vos tailleurs Vous qui pr\u00e9tendiez \u00eatre les meilleurs Aujourd&#8217;hui vous tremblez de peur Devant cette chose ...\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.masharif.com\/fr\/2021\/05\/07\/ou-sont-vos-airs-narquois-meprisables-par-ahmed-safir-fes-maroc\/\" \/>\n<meta property=\"og:site_name\" content=\"Culminances\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-07T17:11:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-07T17:11:30+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2021\/05\/kristiano160700037.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"450\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mohamed Salah Ben Amor\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mohamed Salah Ben Amor\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.masharif.com\/fr\/#website\",\"url\":\"http:\/\/www.masharif.com\/fr\/\",\"name\":\"Culminances\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/www.masharif.com\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\/\/www.masharif.com\/fr\/2021\/05\/07\/ou-sont-vos-airs-narquois-meprisables-par-ahmed-safir-fes-maroc\/#primaryimage\",\"url\":\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2021\/05\/kristiano160700037.jpg\",\"contentUrl\":\"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2021\/05\/kristiano160700037.jpg\",\"width\":450,\"height\":450},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.masharif.com\/fr\/2021\/05\/07\/ou-sont-vos-airs-narquois-meprisables-par-ahmed-safir-fes-maroc\/\",\"url\":\"http:\/\/www.masharif.com\/fr\/2021\/05\/07\/ou-sont-vos-airs-narquois-meprisables-par-ahmed-safir-fes-maroc\/\",\"name\":\"O\u00f9 sont vos airs narquois, m\u00e9prisables? par: Ahmed Safir- F\u00e8s -Maroc - Culminances\",\"isPartOf\":{\"@id\":\"http:\/\/www.masharif.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/www.masharif.com\/fr\/2021\/05\/07\/ou-sont-vos-airs-narquois-meprisables-par-ahmed-safir-fes-maroc\/#primaryimage\"},\"datePublished\":\"2021-05-07T17:11:29+00:00\",\"dateModified\":\"2021-05-07T17:11:30+00:00\",\"author\":{\"@id\":\"http:\/\/www.masharif.com\/fr\/#\/schema\/person\/839a7026efe9fa825134097c1041e4a0\"},\"breadcrumb\":{\"@id\":\"http:\/\/www.masharif.com\/fr\/2021\/05\/07\/ou-sont-vos-airs-narquois-meprisables-par-ahmed-safir-fes-maroc\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.masharif.com\/fr\/2021\/05\/07\/ou-sont-vos-airs-narquois-meprisables-par-ahmed-safir-fes-maroc\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.masharif.com\/fr\/2021\/05\/07\/ou-sont-vos-airs-narquois-meprisables-par-ahmed-safir-fes-maroc\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/www.masharif.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O\u00f9 sont vos airs narquois, m\u00e9prisables? par: Ahmed Safir- F\u00e8s -Maroc\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/www.masharif.com\/fr\/#\/schema\/person\/839a7026efe9fa825134097c1041e4a0\",\"name\":\"Mohamed Salah Ben Amor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"http:\/\/www.masharif.com\/fr\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/0.gravatar.com\/avatar\/f64806401ad5ed604ffec2272b19ef46?s=96&d=identicon&r=g\",\"contentUrl\":\"http:\/\/0.gravatar.com\/avatar\/f64806401ad5ed604ffec2272b19ef46?s=96&d=identicon&r=g\",\"caption\":\"Mohamed Salah Ben Amor\"},\"sameAs\":[\"http:\/\/ben-amor.info\"],\"url\":\"http:\/\/www.masharif.com\/fr\/author\/msba\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O\u00f9 sont vos airs narquois, m\u00e9prisables? par: Ahmed Safir- F\u00e8s -Maroc - Culminances","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.masharif.com\/fr\/2021\/05\/07\/ou-sont-vos-airs-narquois-meprisables-par-ahmed-safir-fes-maroc\/","og_locale":"fr_FR","og_type":"article","og_title":"O\u00f9 sont vos airs narquois, m\u00e9prisables? par: Ahmed Safir- F\u00e8s -Maroc - Culminances","og_description":"O\u00f9 sont vos airs narquois, m\u00e9prisables A quoi sert v\u00f4tre fortune in\u00e9puisable Vous qui avez longtemps m\u00e9pris\u00e9 vos semblables O\u00f9 sont vos airs de grandeur Vos faux airs de grands seigneurs Vos parfums import\u00e9s d&#8217;ailleurs Vos voitures de luxe, vos tailleurs Vous qui pr\u00e9tendiez \u00eatre les meilleurs Aujourd&#8217;hui vous tremblez de peur Devant cette chose ...","og_url":"http:\/\/www.masharif.com\/fr\/2021\/05\/07\/ou-sont-vos-airs-narquois-meprisables-par-ahmed-safir-fes-maroc\/","og_site_name":"Culminances","article_published_time":"2021-05-07T17:11:29+00:00","article_modified_time":"2021-05-07T17:11:30+00:00","og_image":[{"width":450,"height":450,"url":"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2021\/05\/kristiano160700037.jpg","type":"image\/jpeg"}],"author":"Mohamed Salah Ben Amor","twitter_card":"summary","twitter_misc":{"\u00c9crit par":"Mohamed Salah Ben Amor"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/www.masharif.com\/fr\/#website","url":"http:\/\/www.masharif.com\/fr\/","name":"Culminances","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/www.masharif.com\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/www.masharif.com\/fr\/2021\/05\/07\/ou-sont-vos-airs-narquois-meprisables-par-ahmed-safir-fes-maroc\/#primaryimage","url":"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2021\/05\/kristiano160700037.jpg","contentUrl":"http:\/\/www.masharif.com\/fr\/wp-content\/uploads\/2021\/05\/kristiano160700037.jpg","width":450,"height":450},{"@type":"WebPage","@id":"http:\/\/www.masharif.com\/fr\/2021\/05\/07\/ou-sont-vos-airs-narquois-meprisables-par-ahmed-safir-fes-maroc\/","url":"http:\/\/www.masharif.com\/fr\/2021\/05\/07\/ou-sont-vos-airs-narquois-meprisables-par-ahmed-safir-fes-maroc\/","name":"O\u00f9 sont vos airs narquois, m\u00e9prisables? par: Ahmed Safir- F\u00e8s -Maroc - Culminances","isPartOf":{"@id":"http:\/\/www.masharif.com\/fr\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.masharif.com\/fr\/2021\/05\/07\/ou-sont-vos-airs-narquois-meprisables-par-ahmed-safir-fes-maroc\/#primaryimage"},"datePublished":"2021-05-07T17:11:29+00:00","dateModified":"2021-05-07T17:11:30+00:00","author":{"@id":"http:\/\/www.masharif.com\/fr\/#\/schema\/person\/839a7026efe9fa825134097c1041e4a0"},"breadcrumb":{"@id":"http:\/\/www.masharif.com\/fr\/2021\/05\/07\/ou-sont-vos-airs-narquois-meprisables-par-ahmed-safir-fes-maroc\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.masharif.com\/fr\/2021\/05\/07\/ou-sont-vos-airs-narquois-meprisables-par-ahmed-safir-fes-maroc\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.masharif.com\/fr\/2021\/05\/07\/ou-sont-vos-airs-narquois-meprisables-par-ahmed-safir-fes-maroc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/www.masharif.com\/fr\/"},{"@type":"ListItem","position":2,"name":"O\u00f9 sont vos airs narquois, m\u00e9prisables? par: Ahmed Safir- F\u00e8s -Maroc"}]},{"@type":"Person","@id":"http:\/\/www.masharif.com\/fr\/#\/schema\/person\/839a7026efe9fa825134097c1041e4a0","name":"Mohamed Salah Ben Amor","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"http:\/\/www.masharif.com\/fr\/#\/schema\/person\/image\/","url":"http:\/\/0.gravatar.com\/avatar\/f64806401ad5ed604ffec2272b19ef46?s=96&d=identicon&r=g","contentUrl":"http:\/\/0.gravatar.com\/avatar\/f64806401ad5ed604ffec2272b19ef46?s=96&d=identicon&r=g","caption":"Mohamed Salah Ben Amor"},"sameAs":["http:\/\/ben-amor.info"],"url":"http:\/\/www.masharif.com\/fr\/author\/msba\/"}]}},"_links":{"self":[{"href":"http:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/posts\/11328"}],"collection":[{"href":"http:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/comments?post=11328"}],"version-history":[{"count":1,"href":"http:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/posts\/11328\/revisions"}],"predecessor-version":[{"id":11330,"href":"http:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/posts\/11328\/revisions\/11330"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/media\/11329"}],"wp:attachment":[{"href":"http:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/media?parent=11328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/categories?post=11328"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.masharif.com\/fr\/wp-json\/wp\/v2\/tags?post=11328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}